{"id":187215,"date":"2023-10-31T00:00:00","date_gmt":"2023-10-30T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/la-task-force-indisponibilites-de-lafmps-formule-des-recommandations-pour-lutilisation-des-analogues-du-glp-1\/"},"modified":"2026-08-27T15:10:48","modified_gmt":"2026-08-27T13:10:48","slug":"la-task-force-indisponibilites-de-lafmps-formule-des-recommandations-pour-lutilisation-des-analogues-du-glp-1","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/la-task-force-indisponibilites-de-lafmps-formule-des-recommandations-pour-lutilisation-des-analogues-du-glp-1\/","title":{"rendered":"La Task Force \u00ab Indisponibilit\u00e9s \u00bb de l\u2019AFMPS formule des recommandations pour l\u2019utilisation des analogues du GLP-1"},"content":{"rendered":"<p>La\u00a0<strong>Task Force \u00ab\u00a0Indisponibilit\u00e9s\u00a0\u00bb<\/strong>\u00a0de l\u2019Agence f\u00e9d\u00e9rale des m\u00e9dicaments et des produits de sant\u00e9 (AFMPS) formule des recommandations pour l\u2019utilisation des analogues du GLP-1 (e.a. le s\u00e9maglutide)\u00a0: voir\u00a0<a href='https:\/\/www.afmps.be\/fr\/news\/disponibilite_limitee_des_analogues_du_glp_1_recommandations_pour_les_medecins_specialistes' target='_blank'>Disponibilit\u00e9 limit\u00e9e des analogues du GLP-1 : recommandations pour les m\u00e9decins (sp\u00e9cialistes)&#x002C; les pharmaciens (d\u2019h\u00f4pitaux) et les patients<\/a>\u00a0(communiqu\u00e9 du 26\/10\/2023).<br \/> D\u2019apr\u00e8s la Task Force : \u00ab\u00a0<em>Tant que la disponibilit\u00e9 est limit\u00e9e&#x002C; la priorit\u00e9 doit \u00eatre donn\u00e9e \u00e0 l&#39;indication autoris\u00e9e des analogues du GLP-1 pour le traitement du diab\u00e8te de type 2&#x002C; \u00e0 savoir le traitement des patients adultes dont le diab\u00e8te de type 2 n\u2019est pas suffisamment r\u00e9gul\u00e9&#x002C; en compl\u00e9ment d\u2019un r\u00e9gime alimentaire et d\u2019exercice physique<\/em>\u00a0\u00bb.\u00a0\u00a0La Task Force propose \u00e9galement d\u2019envisager l\u2019usage de quelques-uns de ces analogues chez certaines personnes souffrant d\u2019ob\u00e9sit\u00e9 (morbide).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0Task Force \u00ab\u00a0Indisponibilit\u00e9s\u00a0\u00bb\u00a0de l\u2019Agence f\u00e9d\u00e9rale des m\u00e9dicaments et des produits  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-187215","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=187215"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187215\/revisions"}],"predecessor-version":[{"id":189770,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187215\/revisions\/189770"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=187215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=187215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=187215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}