{"id":187197,"date":"2024-01-10T00:00:00","date_gmt":"2024-01-09T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/le-repertoire-edition-2024-premiere-serie-de-chapitres-mis-a-jour\/"},"modified":"2026-07-09T15:12:31","modified_gmt":"2026-07-09T13:12:31","slug":"le-repertoire-edition-2024-premiere-serie-de-chapitres-mis-a-jour","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/le-repertoire-edition-2024-premiere-serie-de-chapitres-mis-a-jour\/","title":{"rendered":"Le R\u00e9pertoire &lsquo;\u00e9dition 2024&rsquo;: premi\u00e8re s\u00e9rie de chapitres mis \u00e0 jour"},"content":{"rendered":"<p>La r\u00e9vision annuelle du R\u00e9pertoire se fait progressivement&#x002C; par \u00e9tapes successives r\u00e9parties sur l\u2019ann\u00e9e. Une premi\u00e8re s\u00e9rie de chapitres vient d\u2019\u00eatre mise \u00e0 jour\u00a0et publi\u00e9e en ligne: <strong>Syst\u00e8me cardio-vasculaire<\/strong>&#x002C; <strong>Syst\u00e8me gastro-intestinal<\/strong>&#x002C; <strong>Syst\u00e8me urog\u00e9nital<\/strong>&#x002C; <strong>Immunit\u00e9<\/strong>&#x002C; <strong>Min\u00e9raux et vitamines<\/strong>&#x002C; <strong>Dermatologie<\/strong>&#x002C; <strong>Agents de diagnostic<\/strong>. Les autres chapitres suivront dans les mois \u00e0 venir (en mars et juin 2024).<\/p>\n<p> Dans ces chapitres&#x002C; la rubrique &lsquo;<i>Positionnement<\/i>&lsquo; et d&#39;autres rubriques ont \u00e9t\u00e9 mises \u00e0 jour. Comme chaque ann\u00e9e&#x002C; cette mise \u00e0 jour a \u00e9t\u00e9 r\u00e9alis\u00e9e avec l\u2019aide de nombreux experts. Vous trouverez de plus amples informations sur le contenu et la m\u00e9thodologie des rubriques des diff\u00e9rents chapitres dans l\u2019Introduction du R\u00e9pertoire (voir\u00a0<a href='https:\/\/www.cbip.be\/fr\/chapters\/1?frag=9990029'>Intro.2. Guide d\u2019utilisation du R\u00e9pertoire<\/a>).<\/p>\n<p>Les principales nouveaut\u00e9s des chapitres mis \u00e0 jour sont d\u00e9taill\u00e9es ci-dessous.<\/p>\n<ul>\n<li>\n<p><b>La rubrique \u00ab\u00a0Grossesse et allaitement\u00a0\u00bb<\/b><\/p>\n<ul>\n<li>\n<p>L\u2019ann\u00e9e derni\u00e8re&#x002C; nous avions remani\u00e9 la rubrique Grossesse dans les chapitres <i>Syst\u00e8me gastro-intestinal <\/i>et<i> Dermatologie<\/i> (ainsi que dans les chapitres<i> Syst\u00e8me respiratoire<\/i> et<i> Oto-rhino-laryngologie<\/i>)<i>. <\/i>Cette rubrique a d\u00e9sormais \u00e9galement \u00e9t\u00e9 adapt\u00e9e dans les chapitres<i> Syst\u00e8me cardio-vasculaire&#x002C; Syst\u00e8me urog\u00e9nital&#x002C; Immunit\u00e9 (partie vaccins)&#x002C; Min\u00e9raux et vitamines <\/i>et<i> Agents de diagnostic<\/i>. Dans les ann\u00e9es \u00e0 venir&#x002C; cette rubrique sera \u00e9galement adapt\u00e9e dans les autres chapitres&#x002C; sur le m\u00eame mod\u00e8le.<\/p>\n<\/li>\n<li>\n<p>La m\u00e9thodologie et les sources utilis\u00e9es pour ce travail de mise \u00e0 jour sont les m\u00eames que celles que nous avons coutume d\u2019utiliser pour cette rubrique (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/1?frag=9990532'>Intro.2.1.5.<\/a>).<\/p>\n<\/li>\n<li>\n<p>Jusqu&#39;\u00e0 pr\u00e9sent&#x002C; cette rubrique \u00e9tait seulement mentionn\u00e9e pour les m\u00e9dicaments qui avaient \u00e9t\u00e9 clairement associ\u00e9s \u00e0 un effet n\u00e9faste chez l\u2019humain. D\u00e9sormais&#x002C; tous les m\u00e9dicaments auront une rubrique \u00ab Grossesse \u00bb. En l\u2019absence d\u2019indices clairs d\u2019effets n\u00e9fastes chez l\u2019humain&#x002C; nous distinguons les m\u00e9dicaments dont l\u2019utilisation pendant la grossesse est consid\u00e9r\u00e9e comme s\u00fbre et les m\u00e9dicaments dont la s\u00e9curit\u00e9 d\u2019emploi pendant la grossesse ne peut \u00eatre \u00e9valu\u00e9e (en raison du manque de donn\u00e9es).<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Syst\u00e8me cardio-vasculaire<\/b><\/p>\n<ul>\n<li>\n<p>La rubrique<i> \u201cGrossesse et allaitement\u201d <\/i>a \u00e9t\u00e9 syst\u00e9matiquement ajout\u00e9e lorsque cela \u00e9tait pertinent (voir ci-dessus).<\/p>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/2?frag=26'>1.1. Hypertension<\/a><\/p>\n<ul>\n<li>\n<p>Nous avons supprim\u00e9 le message selon lequel les antihypertenseurs pourraient \u00eatre plus efficaces s&#39;ils sont pris au coucher.\u00a0Suite \u00e0 la publication de l&#39;\u00e9tude TIME&#x002C; on ne dispose pas de preuves suffisantes que le moment de prise (le matin ou au coucher) influence leur efficacit\u00e9.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/2?frag=1537'>1.12. Hypolipid\u00e9miants<\/a><\/p>\n<ul>\n<li>\n<p>Nous mentionnons les premiers r\u00e9sultats d&#39;\u00e9tude \u00e9valuant l&#39;acide b\u00e9mp\u00e9do\u00efque sur des crit\u00e8res d\u2019\u00e9valuation cardiovasculaires forts. La place de l&#39;acide b\u00e9mp\u00e9do\u00efque par rapport \u00e0 d&#39;autres hypolipid\u00e9miants reste toutefois \u00e0 \u00e9lucider.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Syst\u00e8me gastro-intestinal<\/b><\/p>\n<ul>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/4?frag=2493'>3.1. Pathologie gastrique et duod\u00e9nale<\/a><\/p>\n<ul>\n<li>\n<p>Des \u00e9tudes observationnelles ont montr\u00e9 une diminution des saignements digestifs en cas de prise d\u2019IPP chez des patients \u00e0 risque \u00e9lev\u00e9 d\u2019h\u00e9morragies digestives trait\u00e9s par\u00a0anticoagulants oraux.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Syst\u00e8me urog\u00e9nital <\/b><\/p>\n<ul>\n<li>\n<p>La rubrique<b> <\/b>&lsquo;<i>Grossesse et allaitement<\/i>&lsquo; a \u00e9t\u00e9 syst\u00e9matiquement ajout\u00e9e lorsque cela \u00e9tait pertinent (voir ci-dessus).<\/p>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/8?frag=6304'>7.3. Troubles de l&#39;\u00e9rection<\/a><\/p>\n<ul>\n<li>\n<p>Dans la rubrique &lsquo;<em>Positionnement&rsquo;<\/em>&#x002C; nous pr\u00e9cisons les m\u00e9dicaments qui sont susceptibles de provoquer des dysfonctions \u00e9rectiles.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Immunit\u00e9<\/b><\/p>\n<ul>\n<li>\n<p>Dans le sous-chapitre 12.1. Vaccins&#x002C; la rubrique &lsquo;<em>Grossesse et allaitement<\/em>&lsquo; a \u00e9t\u00e9 syst\u00e9matiquement ajout\u00e9e lorsque cela \u00e9tait pertinent (voir ci-dessus).<\/p>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=11254'>12.1.1. Vaccins antiviraux<\/a><\/p>\n<ul>\n<li>\n<p>Par souci de clart\u00e9&#x002C; le vaccin contre la varicelle et le vaccin contre le zona sont d\u00e9sormais abord\u00e9s dans deux sous-chapitres distincts&#x002C; leur groupe cible et l&#39;effet vis\u00e9 \u00e9tant diff\u00e9rents.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=12245'>12.3.2.3. Interf\u00e9rons<\/a><\/p>\n<ul>\n<li>\n<p>Compte tenu des diff\u00e9rences importantes entre l&#39;interf\u00e9ron alfa et l&#39;interf\u00e9ron b\u00eata&#x002C; ceux-ci sont d\u00e9sormais abord\u00e9s dans deux sous-chapitres distincts.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8904120'>12.3.2.5.1. Inhibiteurs de JAK<\/a><\/p>\n<ul>\n<li>\n<p>Le dernier anti-JAK&#x002C; le deucravacitinib&#x002C; inhibiteur de la TYK2&#x002C; a un m\u00e9canisme d&#39;action et un profil d\u2019innocuit\u00e9 diff\u00e9rents des autres inhibiteurs de JAK. Nous abordons donc cette classe de m\u00e9dicaments en deux sous-chapitres distincts&#x002C; \u00e0 savoir Inhibiteurs de JAK 1\/2\/3 et Inhibiteurs de TYK2.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8904278'>12.3.2.6. Inhibiteurs du compl\u00e9ment<\/a><\/p>\n<ul>\n<li>\n<p>Cette nouvelle classe de m\u00e9dicaments fait d\u00e9sormais l\u2019objet d\u2019un sous-chapitre distinct dans le R\u00e9pertoire.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Min\u00e9raux et vitamines<\/b><\/p>\n<ul>\n<li>\n<p>La rubrique &lsquo;<em>Grossesse et allaitement<\/em>&lsquo; a \u00e9t\u00e9 syst\u00e9matiquement ajout\u00e9e lorsque cela \u00e9tait pertinent (voir ci-dessus)&#x002C; notamment pour les pr\u00e9parations \u00e0 base de fer (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/15?frag=13276'>14.1.1. Fer<\/a>).<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Dermatologie<\/b><\/p>\n<ul>\n<li>\n<p><a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=8904310'>15.4. Ecz\u00e9ma<\/a><\/p>\n<ul>\n<li>\n<p>Un nouveau sous-chapitre d\u00e9di\u00e9\u00a0enti\u00e8rement \u00e0 l\u2019ecz\u00e9ma a \u00e9t\u00e9 cr\u00e9\u00e9&#x002C; bas\u00e9 sur notre article <a href='https:\/\/www.cbip.be\/fr\/articles\/3982?folia=3979'>Folia de janvier 2023<\/a>.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p><b>Agents de diagnostic<\/b><\/p>\n<ul>\n<li>\n<p>La rubrique &lsquo;<em>Grossesse et allaitement<\/em>&lsquo; a \u00e9t\u00e9 syst\u00e9matiquement ajout\u00e9e lorsque cela \u00e9tait pertinent (voir ci-dessus)&#x002C; notamment pour les agents de radiodiagnostic (zie <a href='https:\/\/www.cbip.be\/fr\/chapters\/20?frag=16162'>19.1. Agents de radiodiagnostic<\/a>).<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e9vision annuelle du R\u00e9pertoire se fait progressivement&#x002C; par \u00e9tapes  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,20295],"tags":[20213,20224],"class_list":["post-187197","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2024-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=187197"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187197\/revisions"}],"predecessor-version":[{"id":189753,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/187197\/revisions\/189753"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=187197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=187197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=187197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}