{"id":186944,"date":"2019-05-07T00:00:00","date_gmt":"2019-05-06T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/patients-souffrant-de-douleurs-dentaires-un-groupe-a-risque-important-pour-une-intoxication-accidentelle-au-paracetamol\/"},"modified":"2026-08-27T15:10:40","modified_gmt":"2026-08-27T13:10:40","slug":"patients-souffrant-de-douleurs-dentaires-un-groupe-a-risque-important-pour-une-intoxication-accidentelle-au-paracetamol","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/patients-souffrant-de-douleurs-dentaires-un-groupe-a-risque-important-pour-une-intoxication-accidentelle-au-paracetamol\/","title":{"rendered":"Patients souffrant de douleurs dentaires: un groupe \u00e0 risque important pour une intoxication accidentelle au parac\u00e9tamol"},"content":{"rendered":"<div class='summary'>Les patients souffrant de douleurs dentaires semblent constituer un groupe &agrave; risque important pour une intoxication accidentelle au parac&eacute;tamol. Une prise trop fr&eacute;quente de parac&eacute;tamol &agrave; doses trop &eacute;lev&eacute;es (attention aux nombreuses associations qui contiennent du parac&eacute;tamol!) peut entra&icirc;ner une h&eacute;patotoxicit&eacute; grave&#x002C; particuli&egrave;rement en pr&eacute;sence de facteurs de risque. Chez un patient atteint de douleurs dentaires&#x002C; il importe de s&rsquo;informer&#x002C; d&egrave;s le premier contact&#x002C; de la quantit&eacute; d&rsquo;antidouleurs qui a d&eacute;j&agrave; &eacute;t&eacute; ing&eacute;r&eacute;e&#x002C; en particulier de parac&eacute;tamol.<\/div>\n<p>&#8211; Parmi les patients admis aux urgences en raison d&rsquo;une intoxication accidentelle au parac&eacute;tamol&#x002C; les douleurs dentaires constituent la raison principale de la prise de parac&eacute;tamol. C&rsquo;est ce qui ressort de plusieurs &eacute;tudes observationnelles&#x002C; provenant notamment des Etats-Unis (&eacute;tude cas-t&eacute;moins<span class='folia-referentie-note'>1<\/span>)&#x002C; de la France (notifications spontan&eacute;es<span class='folia-referentie-note'>2<\/span>) et du Royaume-Uni (&eacute;tude de cohorte r&eacute;trospective<span class='folia-referentie-note'>3<\/span>). Au moment o&ugrave; un patient atteint de douleurs dentaires contacte un m&eacute;decin&#x002C; un dentiste ou un pharmacien&#x002C; il est important de lui demander s&rsquo;il a d&eacute;j&agrave; pris des antidouleurs&#x002C; en particulier du parac&eacute;tamol&#x002C; et en quelle quantit&eacute;. Des donn&eacute;es indiquent en effet que les patients souffrant de douleurs dentaires prennent parfois pendant trop longtemps et trop fr&eacute;quemment du parac&eacute;tamol&#x002C; parfois &agrave; doses trop &eacute;lev&eacute;es&#x002C; risquant ainsi une intoxication au parac&eacute;tamol.<\/p>\n<p>&#8211; Le fait de retarder trop longtemps les visites chez le dentiste (par exemple par crainte d&rsquo;une intervention ou parce que le co&ucirc;t constitue un obstacle) ou l&rsquo;acc&egrave;s difficile aux soins dentaires urgents sont des facteurs qui peuvent jouer un r&ocirc;le dans la consommation excessive de parac&eacute;tamol par les patients souffrant de douleurs dentaires. Par ailleurs&#x002C; le patient combine&#x002C; parfois sans s&rsquo;en rendre compte&#x002C; plusieurs m&eacute;dicaments contenant du parac&eacute;tamol. Il existe en effet de nombreuses associations dont on oublie parfois qu&rsquo;elles contiennent du parac&eacute;tamol. Nombre de m&eacute;dicaments contenant du parac&eacute;tamol sont en vente libre&#x002C; ce qui peut faire penser &agrave; tort au patient que le m&eacute;dicament est inoffensif. Des conditionnements contenant au total plus de 10&#x002C;05 grammes de parac&eacute;tamol ne sont disponibles que sur prescription ou sur &ldquo;demande &eacute;crite du patient&rdquo;&#x002C; mais comme nous l&rsquo;&eacute;crivions dans les <a href='https:\/\/www.cbip.be\/fr\/articles\/1271?folia=1207'>Folia de d&eacute;cembre 2003<\/a> la question reste de savoir si le fait d&rsquo;exiger une demande &eacute;crite permet d&rsquo;&eacute;viter les probl&egrave;mes li&eacute;s &agrave; un surdosage de parac&eacute;tamol.<\/p>\n<div class='detailed-content'>&#8211; Le parac&eacute;tamol existe comme <strong>sp&eacute;cialit&eacute; monocompos&eacute;e<\/strong> sous de nombreux <a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=mps-6429'><u>noms de sp&eacute;cialit&eacute;<\/u><\/a>; il y a aussi de nombreuses <strong>associations<\/strong> contenant du parac&eacute;tamol (situation au 1\/1\/2018):<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (400 mg \/ 500 mg) + caf&eacute;ine<\/u> : Algostase&reg;&#x002C; Antigriphine&reg;&#x002C; Lonarid N&reg;&#x002C; Mann&reg;&#x002C; Panadol Plus&reg;&#x002C; Croix Blanche&reg;.<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (200 mg \/ 250 mg \/ 400 mg) + acide ac&eacute;tylsalicylique + caf&eacute;ine<\/u> : Excedryn&reg;&#x002C; Perdolan Compositum&reg;&#x002C; Troc&reg;<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (200 mg) + acide ac&eacute;tylsalicylique + acide ascorbique<\/u> : Afebryl&reg;<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (500 mg) + cod&eacute;ine<\/u> : Algocod&reg;&#x002C; Dafalgan Codeine&reg;.<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (500 mg) + cod&eacute;ine + caf&eacute;ine<\/u>&nbsp;: Nevrine Codeine&reg;.<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (325 mg) + tramadol<\/u> : Algotra&reg;&#x002C; Pontalsic&reg;&#x002C; Tramadol\/Parac&eacute;tamol EG&#x002C; Tramadol\/Parac&eacute;tamol KrKa&reg;&#x002C; Tramadol\/Parac&eacute;tamol Sandoz&reg;&#x002C; Tramadol\/Parac&eacute;tamol Teva&reg;&#x002C; Zaldiar&reg;.<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (500 mg) + pseudo-&eacute;ph&eacute;drine<\/u> : Niocitran&reg;&#x002C; Parasineg&reg;&#x002C; Sinutab&reg;.<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (240 mg) + chlorph&eacute;namine<\/u> : Rhinofebryl&reg;<br \/> &nbsp; &nbsp; &bull; <u>parac&eacute;tamol (33&#x002C;3 mg\/ 5 ml) + benzoate + gua&iuml;f&eacute;n&eacute;sine + oxom&eacute;mazine<\/u> : Toplexil&reg;<br \/> &#8211; La sp&eacute;cialit&eacute; &agrave; base de parac&eacute;tamol &agrave; lib&eacute;ration modifi&eacute;e (Panadol Retard&reg;) sera probablement retir&eacute;e du march&eacute; en 2018 (voir aussi la Note au bas de cet article).<\/div>\n<p>&#8211; On sait que le parac&eacute;tamol&#x002C; en cas de surdosage aigu (&agrave; partir de 10 grammes chez un adulte&#x002C; &agrave; partir de 150 mg\/kg chez l&rsquo;enfant)&#x002C; peut provoquer une atteinte h&eacute;patique grave&#x002C; n&eacute;cessitant parfois une greffe h&eacute;patique ou pouvant m&ecirc;me avoir une issue fatale. Cependant&#x002C; une atteinte h&eacute;patique grave peut &eacute;galement survenir en cas de prises r&eacute;p&eacute;t&eacute;es de doses suprath&eacute;rapeutiques. Des donn&eacute;es am&eacute;ricaines ont r&eacute;v&eacute;l&eacute; qu&rsquo;en cas de prises r&eacute;p&eacute;t&eacute;es&#x002C; la dose journali&egrave;re m&eacute;diane de parac&eacute;tamol associ&eacute;e &agrave; une h&eacute;patotoxicit&eacute; &eacute;tait de 5 &agrave; 7&#x002C;5 g par jour. En pr&eacute;sence de facteurs de risque&#x002C; une h&eacute;patotoxicit&eacute; peut d&eacute;j&agrave; appara&icirc;tre en cas de doses moins &eacute;lev&eacute;es de parac&eacute;tamol ing&eacute;r&eacute;&#x002C; aussi bien apr&egrave;s un surdosage aigu qu&rsquo;apr&egrave;s un usage chronique [voir <a href='https:\/\/www.cbip.be\/fr\/articles\/query?number=F38N04F'>Folia d&#39;avril 2011<\/a>]. Parmi les facteurs de risque&#x002C; on compte le je&ucirc;ne&#x002C; la malnutrition chronique&#x002C; un faible poids corporel (&lt; 50 kg chez l&rsquo;adulte)&#x002C; un &acirc;ge avanc&eacute;&#x002C; une insuffisance h&eacute;patique&#x002C; la d&eacute;pendance &agrave; l&rsquo;alcool&#x002C; une insuffisance r&eacute;nale grave. L&rsquo;utilisation d&rsquo;inducteurs enzymatiques des CYP (carbamaz&eacute;pine&#x002C; ph&eacute;nyto&iuml;ne&#x002C; ph&eacute;nobarbital&#x002C; primidone&#x002C; rifampicine) pourrait &eacute;galement constituer un facteur de risque.<\/p>\n<div class='detailed-content'>L&rsquo;h&eacute;patoxicit&eacute; du parac&eacute;tamol est provoqu&eacute;e par un m&eacute;tabolite (N-ac&eacute;tyl-p-benzoquinone-imine ou NAPQI) qui ne se forme que de mani&egrave;re limit&eacute;e en circonstances normales et qui est enti&egrave;rement neutralis&eacute; par liaison au glutathion. En cas de surproduction du m&eacute;tabolite (p.ex. en cas de surdosage) ou en cas de d&eacute;ficit en glutathion (p.ex. en cas de je&ucirc;ne ou de malnutrition)&#x002C; le glutathion disponible est rapidement satur&eacute;&#x002C; et le m&eacute;tabolite non li&eacute; est en mesure d&rsquo;exercer son action toxique sur le foie [voir aussi le <a href='https:\/\/www.centreantipoisons.be\/professionnels-de-la-sant\/articles-pour-professionnels-de-la-sant\/traitement-des-intoxications-au'>site Web du Centre Antipoisons<\/a>].<\/div>\n<p>&#8211; Il est essentiel de s&rsquo;informer&#x002C; d&egrave;s le premier contact d&ucirc; &agrave; des douleurs dentaires&#x002C; sur la quantit&eacute; de parac&eacute;tamol d&eacute;j&agrave; ing&eacute;r&eacute;e. En effet&#x002C; le patient atteint d&rsquo;une intoxication au parac&eacute;tamol peut rester enti&egrave;rement asymptomatique durant les premi&egrave;res 24&nbsp;heures&#x002C; ou ne pr&eacute;senter que des sympt&ocirc;mes non sp&eacute;cifiques (naus&eacute;es&#x002C; vomissements&#x002C; malaise)&#x002C; les signes d&rsquo;une atteinte h&eacute;patique (douleur au quadrant sup&eacute;rieur droit&#x002C; ict&egrave;re&#x002C; enc&eacute;phalopathie h&eacute;patique) ne survenant qu&rsquo;ult&eacute;rieurement. En cas de suspicion d&rsquo;une intoxication au parac&eacute;tamol&#x002C; un renvoi rapide vers les services d&rsquo;urgences s&rsquo;impose&#x002C; associ&eacute; si n&eacute;cessaire &agrave; l&rsquo;administration par voie intraveineuse de N-ac&eacute;tylcyst&eacute;ine&#x002C; donneur de glutathion. [Les d&eacute;tails concernant la prise en charge d&rsquo;une intoxication au parac&eacute;tamol sortent du cadre du pr&eacute;sent article; nous vous renvoyons pour cela au <a href='https:\/\/www.centreantipoisons.be\/professionnels-de-la-sant\/articles-pour-professionnels-de-la-sant\/traitement-des-intoxications-au'>site Web du Centre Antipoisons<\/a>].<\/p>\n<p>&#8211; Le parac&eacute;tamol constitue le premier choix pour le traitement symptomatique des douleurs nociceptives (non neuropathiques) et de la fi&egrave;vre&#x002C; mais il convient de ne jamais perdre de vue le danger d&rsquo;intoxication. Il est important de respecter la posologie.<\/p>\n<p> <strong>Posologie<\/strong> <\/p>\n<ul>\n<li>\n<p>Adulte &ge; 50 kg:<\/p>\n<ul>\n<li>\n<p>par voie orale : 500 mg &agrave; 1 g&#x002C; jusqu&rsquo;&agrave; 4 x p.j.&#x002C; maximum 4 g p.j.; en pr&eacute;sence de facteurs de risque* maximum 3 g p.j.; en cas d&rsquo;insuffisance r&eacute;nale&#x002C; respecter un intervalle de 6 &agrave; 8 heures entre les doses.<\/p>\n<\/li>\n<li>\n<p>par voie parent&eacute;rale : jusqu&rsquo;&agrave; maximum 4 x 1 g p.j.&#x002C; moins en pr&eacute;sence de facteurs de risque*<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p>Enfant et adulte &lt; 50 kg:<\/p>\n<ul>\n<li>\n<p>par voie orale&nbsp;: 15 mg\/kg jusqu&rsquo;&agrave; 4 x p.j. ou 10 mg\/kg jusqu&rsquo;&agrave; 6 x p.j.&#x002C; maximum 60 mg\/kg\/jour; chez l&rsquo;adulte &lt; 50 kg avec facteurs de risque*: maximum 2 g p.j.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><em>* les facteurs de risque pour l&rsquo;h&eacute;patotoxicit&eacute; sont entre autres : je&ucirc;ne&#x002C; malnutrition chronique&#x002C; &acirc;ge avanc&eacute;&#x002C; insuffisance h&eacute;patique&#x002C; alcoolisme chronique&#x002C; insuffisance r&eacute;nale s&eacute;v&egrave;re [voir aussi <a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=6429'>R&eacute;pertoire&#x002C; chapitre 8.2.1.<\/a>]<\/em><\/p>\n<p>&#8211; Il est possible qu&rsquo;en plus du parac&eacute;tamol&#x002C; d&rsquo;autres analg&eacute;siques (par exemple l&rsquo;acide ac&eacute;tylsalicylique&#x002C; l&rsquo;ibuprof&egrave;ne&#x002C; le tramadol etc.) puissent parfois &ecirc;tre ing&eacute;r&eacute;s de mani&egrave;re excessive en cas de douleurs dentaires et &eacute;galement entra&icirc;ner des intoxications accidentelles.<\/p>\n<p> &nbsp; <\/p>\n<h2>Note<\/h2>\n<p>Contrairement &agrave; ce que l&rsquo;on pense parfois&#x002C; la prise r&eacute;p&eacute;t&eacute;e de doses suprath&eacute;rapeutiques de parac&eacute;tamol peut provoquer une intoxication avec de graves l&eacute;sions h&eacute;patiques&#x002C; comme le souligne &agrave; juste titre cet article. Un surdosage en parac&eacute;tamol n&eacute;cessite une &eacute;valuation urgente pour d&eacute;terminer si l&rsquo;administration de l&rsquo;antidote N-ac&eacute;tylcyst&eacute;ine est utile. Cette &eacute;valuation lors de cette prise r&eacute;p&eacute;t&eacute;e n&rsquo;est pas facile &agrave; r&eacute;aliser car&#x002C; contrairement &agrave; une intoxication aigu&euml;&#x002C; on ne peut pas se fier &agrave; un nomogramme contenant la concentration plasmatique du parac&eacute;tamol. L&rsquo;&eacute;valuation doit se faire sur base d&rsquo;une estimation des risques de troubles h&eacute;patiques&#x002C; qui doit se baser sur plusieurs facteurs. Dans ce contexte&#x002C; nous aimerions souligner qu&rsquo;en cas de surdosage de parac&eacute;tamol avec une pr&eacute;paration &agrave; lib&eacute;ration modifi&eacute;e (Panadol Retard&reg;)&#x002C; il est d&eacute;j&agrave; question d&rsquo;une exposition r&eacute;p&eacute;t&eacute;e d&egrave;s l&rsquo;apport initial&#x002C; avec les m&ecirc;mes probl&egrave;mes mentionn&eacute;s ci-dessus concernant l&rsquo;&eacute;valuation d&rsquo;une administration de N-ac&eacute;tylcyst&eacute;ine. De plus&#x002C; il peut y avoir confusion parce que le patient ne communiquera pas toujours s&rsquo;il prenait d&eacute;j&agrave; ou non une pr&eacute;paration &agrave; lib&eacute;ration modifi&eacute;e ou peut-&ecirc;tre m&ecirc;me une combinaison des deux. L&#39;Agence europ&eacute;enne des m&eacute;dicaments (EMA) a r&eacute;cemment d&eacute;cid&eacute;&#x002C; compte tenu des risques excessifs associ&eacute;s au surdosage&#x002C; que les pr&eacute;parations de parac&eacute;tamol &agrave; lib&eacute;ration modifi&eacute;e doivent &ecirc;tre retir&eacute;es du march&eacute; [voir &ldquo;Communiqu&eacute; par le Centre de pharmacovigilance&rdquo; dans ce num&eacute;ro et le <a href='https:\/\/www.ema.europa.eu\/ema\/index.jsp?curl=pages\/news_and_events\/news\/2017\/12\/news_detail_002876.jsp&amp;mid=WC0b01ac058004d5c1'>communiqu&eacute; de l&rsquo;EMA du 15\/12\/17<\/a>].<\/p>\n<h2>Sources g&eacute;n&eacute;rales<\/h2>\n<ul>\n<li class='reference'><span class='folia-referentie-tekst'>Guggenheimer J en Moore PA. The therapeutic applications of and risks associated with acetaminophen use. A review and update. JADA 2011;142(1):38-44<\/span><\/li>\n<li class='reference'><span class='folia-referentie-tekst'>Nayyer NV&#x002C; Byers J en Marney C. Identifying adults at risk of paracetamol toxicity in the acute dental setting: development of a clinical algorithm. British Dental Journal 2014;216:229-35 (doi: <a href='https:\/\/dx.doi.org\/10.1038\/sj.bdj.2014.146'>10.1038\/sj.bdj.2014.146<\/a>)<\/span><\/li>\n<\/ul>\n<h2>Sources sp&eacute;cifiques<\/h2>\n<div class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span>&nbsp;Vogel J&#x002C; Heard KJ&#x002C; Carlson C&#x002C; Lange C en Mitchell G. Dental pain as a risk factor for accidental acetaminophen overdose: A case control study. Am J Emerg Med. 2011;29(9):1125&ndash;9 (doi: <a href='https:\/\/dx.doi.org\/10.1016\/j.ajem.2010.08.006'>10.1016\/j.ajem.2010.08.006<\/a>)<br \/> <span class='folia-referentie-nummer'>2<\/span>&nbsp;Clement C&#x002C; Scala\u2010Bertola J&#x002C; Javot L&#x002C; Royer\u2010Morrot MJ&#x002C; Gillet P et al. Misuse of acetaminophen in the management of dental pain. Pharmacoepidemiology and drug safety 2011; 20: 996&ndash;1000 (doi: <a href='https:\/\/dx.doi.org\/10.1002\/pds.2171'>10.1002\/pds.2171<\/a>)<br \/> <span class='folia-referentie-nummer'>3<\/span>&nbsp;Siddique I&#x002C; Mahmood H en Mohammed-Ali R. Paracetamol overdose secondary to dental pain: a case series. British Dental Journal 2015;219:E6 (doi: <a href='https:\/\/dx.doi.org\/10.1038\/sj.bdj.2015.706'>10.1038\/sj.bdj.2015.706<\/a>)&#x002C; avec commentaire (Rice S. British Dental Journal 2019;263)<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les patients souffrant de douleurs dentaires semblent constituer un groupe  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,62],"tags":[20213,20224],"class_list":["post-186944","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2019-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186944"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186944\/revisions"}],"predecessor-version":[{"id":189500,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186944\/revisions\/189500"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}