{"id":186626,"date":"2023-01-19T00:00:00","date_gmt":"2023-01-18T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/traitement-local-de-leczema-atopique\/"},"modified":"2026-08-27T15:10:28","modified_gmt":"2026-08-27T13:10:28","slug":"traitement-local-de-leczema-atopique","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/traitement-local-de-leczema-atopique\/","title":{"rendered":"Traitement local de l\u2019ecz\u00e9ma atopique"},"content":{"rendered":"<div class='summary'>L&rsquo;ecz&eacute;ma atopique se traite avant tout localement&#x002C; avec une combinaison d&rsquo;&eacute;mollients et de corticost&eacute;ro&iuml;des. Pour le traitement de l&rsquo;ecz&eacute;ma atopique mod&eacute;r&eacute; &agrave; s&eacute;v&egrave;re&#x002C; les pr&eacute;parations de corticost&eacute;ro&iuml;des moyennement puissantes &agrave; puissantes sont plus efficaces que les pr&eacute;parations peu puissantes. Aucune diff&eacute;rence n&#39;est constat&eacute;e entre les pr&eacute;parations puissantes et tr&egrave;s puissantes&#x002C; ni entre les pr&eacute;parations moyennement puissantes et puissantes. &nbsp;La pr&eacute;vention des r&eacute;cidives repose essentiellement sur l&rsquo;application syst&eacute;matique d&#39;&eacute;mollients. Une autre approche bien document&eacute;e chez les patients souffrant de r&eacute;cidives fr&eacute;quentes est le traitement proactif par corticost&eacute;ro&iuml;des topiques (dermocortico&iuml;des).<\/p>\n<p> Dans les formes s&eacute;v&egrave;res d&rsquo;ecz&eacute;ma&#x002C; un traitement local avec des immunomodulateurs (tacrolimus et pim&eacute;crolimus) est parfois envisag&eacute;&#x002C; principalement au niveau des zones sensibles (par exemple autour des yeux&#x002C; dans les plis cutan&eacute;s). Les immunomodulateurs topiques peuvent aussi avoir une place en cas d&rsquo;intol&eacute;rance ou de contre-indication aux corticost&eacute;ro&iuml;des topiques. Les immunomodulateurs&#x002C; qui ne se sont pas av&eacute;r&eacute;s sup&eacute;rieurs aux corticost&eacute;ro&iuml;des dans le traitement de l&rsquo;ecz&eacute;ma&#x002C; sont associ&eacute;s &agrave; un risque major&eacute; de l&eacute;gers effets ind&eacute;sirables locaux (tels que sensation de br&ucirc;lure et prurit) et un co&ucirc;t plus &eacute;lev&eacute;.<\/p><\/div>\n<h2>Introduction<\/h2>\n<p>Le terme <b>ecz&eacute;ma<\/b> d&eacute;signe un groupe de maladies inflammatoires de la peau qui se caract&eacute;risent par une combinaison de prurit et d&rsquo;alt&eacute;rations cutan&eacute;es polymorphes telles que rougeur&#x002C; &oelig;d&egrave;me&#x002C; papules&#x002C; v&eacute;sicules&#x002C; cro&ucirc;tes&#x002C; squames et\/ou lich&eacute;nification. L&rsquo;ecz&eacute;ma atopique&nbsp; est une forme d&rsquo;ecz&eacute;ma chronique d&rsquo;origine g&eacute;n&eacute;tique et s&rsquo;accompagne souvent d&rsquo;autres affections allergiques telles que l&rsquo;asthme et la rhinoconjonctivite. Dans de rares cas&#x002C; l&rsquo;ecz&eacute;ma est caus&eacute; par une allergie alimentaire.<\/p>\n<p>En cas d&rsquo;ecz&eacute;ma atopique&#x002C; la premi&egrave;re &eacute;tape consiste &agrave; &eacute;viter autant que possible <b>les allerg&egrave;nes et les facteurs aggravants<\/b> (par exemple transpiration&#x002C; climat chaud ou froid&#x002C; certains textiles (tissus rugueux comme la laine)&#x002C; maladie&#x002C; stress&#x002C; produits d&rsquo;entretien&#x002C; savon et shampoing). Ces facteurs aggravants n&rsquo;&eacute;tant pas toujours pr&eacute;sents&#x002C; la gravit&eacute; de l&rsquo;affection peut varier.<\/p>\n<p>La <b>gravit&eacute; de l&rsquo;ecz&eacute;ma<\/b> est estim&eacute;e visuellement&#x002C; sur base de la pr&eacute;sentation clinique des alt&eacute;rations cutan&eacute;es telles que rougeurs&#x002C; &oelig;d&egrave;mes&#x002C; papules et l&eacute;sions de grattage. Il existe plusieurs &eacute;chelles valid&eacute;es permettant d&rsquo;&eacute;valuer la gravit&eacute; de l&#39;ecz&eacute;ma.<\/p>\n<div class='detailed-content'>Le Three Item Severity score est particuli&egrave;rement adapt&eacute; &agrave; la pratique quotidienne. Cette &eacute;chelle &eacute;value trois aspects de l&#39;ecz&eacute;ma : la rougeur&#x002C; l&#39;&oelig;d&egrave;me\/les papules et les l&eacute;sions de grattage. Un score de 0 &agrave; 3 est attribu&eacute; &agrave; chacun de ces aspects&#x002C; selon leur s&eacute;v&eacute;rit&eacute; (absent=0&#x002C; l&eacute;ger=1&#x002C; mod&eacute;r&eacute;=2&#x002C; s&eacute;v&egrave;re=3). Les trois scores sont ensuite additionn&eacute;s&nbsp;: un score &lt;&nbsp;3&nbsp;=&nbsp;ecz&eacute;ma l&eacute;ger&#x002C; un score de 3 &agrave; 6&nbsp;=&nbsp;ecz&eacute;ma mod&eacute;r&eacute; et un score&nbsp;&ge;&nbsp;6&nbsp;=&nbsp;ecz&eacute;ma s&eacute;v&egrave;re<span class='folia-referentie-nummer'><sup>1<\/sup><\/span>.<\/p>\n<p> Dans les &eacute;tudes&#x002C; des outils plus complexes sont utilis&eacute;s&#x002C; tels que le SCORAD (<i>SCORing Atopic Dermatitis<\/i>). Le SCORAD est un outil qui &eacute;value l&#39;&eacute;tendue et l&#39;intensit&eacute; des l&eacute;sions ainsi que les sympt&ocirc;mes subjectifs (prurit et troubles de sommeil) sur une &eacute;chelle visuelle analogique<span class='folia-referentie-nummer'><sup>2<\/sup><\/span>.<\/div>\n<p>Le pr&eacute;sent article est une mise &agrave; jour de notre pr&eacute;c&eacute;dent article sur l&rsquo;ecz&eacute;ma atopique (<a href='https:\/\/www.cbip.be\/fr\/articles\/1576?folia=1575'>Folia d&rsquo;avril 2007<\/a>). Nous nous fondons principalement sur les derniers guidelines du NHG<span class='folia-referentie-nummer'><sup>1<\/sup><\/span> (2014) et du NICE (2021)<span class='folia-referentie-nummer'><sup>3<\/sup><\/span>&#x002C; et sur une revue Cochrane r&eacute;cente ayant &eacute;valu&eacute; le traitement topique par corticost&eacute;ro&iuml;des. &nbsp;Seuls les traitements topiques sont abord&eacute;s ici. Dans les formes tr&egrave;s s&eacute;v&egrave;res&#x002C; des immunomodulateurs syst&eacute;miques (tels que certains inhibiteurs d&#39;interleukine ou de Janus kinase) ou des phototh&eacute;rapies sont &eacute;galement utilis&eacute;s.<\/p>\n<h2>Les &eacute;mollients<\/h2>\n<p>Les &eacute;mollients hydratent la peau et att&eacute;nuent le prurit et l&rsquo;irritation. Ils sont utilis&eacute;s pour &eacute;viter les pouss&eacute;es lors des phases plus calmes d&rsquo;ecz&eacute;ma atopique. Les &eacute;mollients sont propos&eacute;s comme traitement de base de l&#39;ecz&eacute;ma. Il est sugg&eacute;r&eacute; de les utiliser en permanence&#x002C; m&ecirc;me lorsque les l&eacute;sions ecz&eacute;mateuses ont disparu. Les guidelines du NICE et du NHG conseillent par exemple une cr&egrave;me au c&eacute;tomacrogol ou une cr&egrave;me lipophile &agrave; base d&rsquo;ur&eacute;e comme &eacute;mollients<span class='folia-referentie-nummer'><sup>1&#x002C;3<\/sup><\/span>. La teneur en graisse du produit est d&eacute;termin&eacute;e sur la base de la s&eacute;cheresse de la peau et des pr&eacute;f&eacute;rences personnelles du patient.<\/p>\n<p>Une revue Cochrane incluant plusieurs RCT conclut que les &eacute;mollients pr&eacute;sentent plusieurs b&eacute;n&eacute;fices prouv&eacute;s: ils prolongent notamment le d&eacute;lai jusqu&rsquo;&agrave; une nouvelle pouss&eacute;e&#x002C; r&eacute;duisent le nombre de pouss&eacute;es et la quantit&eacute; de corticost&eacute;ro&iuml;des n&eacute;cessaire (degr&eacute; de certitude faible &agrave; mod&eacute;r&eacute;)<span class='folia-referentie-nummer'><sup>4<\/sup><\/span>. Les donn&eacute;es probantes disponibles ne permettaient pas de se prononcer en faveur d&rsquo;une cr&egrave;me sp&eacute;cifique. Les &eacute;mollients &eacute;tudi&eacute;s &eacute;taient des cr&egrave;mes &agrave; base d&rsquo;ur&eacute;e&#x002C; d&rsquo;acide glycyrrhizique&#x002C; de glyc&eacute;rol et d&rsquo;avoine. Ces cr&egrave;mes&#x002C; &agrave; l&#39;exception des cr&egrave;mes &agrave; l&#39;ur&eacute;e&#x002C; ne sont pas couramment utilis&eacute;es comme pr&eacute;parations magistrales en Belgique mais elles sont disponibles en vente libre.<\/p>\n<p>Une RCT r&eacute;cente a montr&eacute; que l&#39;application quotidienne d&#39;&eacute;mollients d&egrave;s les premiers jours apr&egrave;s la naissance jusqu&#39;&agrave; l&#39;&acirc;ge de 2 mois r&eacute;duit l&#39;incidence de la dermatite atopique au cours de la premi&egrave;re ann&eacute;e de vie chez les enfants &agrave; haut risque de dermatite atopique<span class='folia-referentie-nummer'><sup>5<\/sup><\/span>.<\/p>\n<h2> Les corticost&eacute;ro&iuml;des en application locale<\/h2>\n<p>Si le traitement avec les &eacute;mollients ne suffit pas&#x002C; des corticost&eacute;ro&iuml;des topiques (dermocortico&iuml;des) sont utilis&eacute;s en traitement de base dans l&rsquo;ecz&eacute;ma atopique.<\/p>\n<p>Le traitement au moyen de dermocortico&iuml;des est parfois source d&rsquo;incertitude&nbsp;: quelle puissance de corticost&eacute;ro&iuml;des faut-il utiliser pour une r&eacute;duction ad&eacute;quate des sympt&ocirc;mes&#x002C; quel v&eacute;hicule privil&eacute;gier en fonction du type d&rsquo;ecz&eacute;ma&#x002C; &agrave; quelle fr&eacute;quence faut-il appliquer le corticost&eacute;ro&iuml;de et pendant combien de temps&#x002C; comment pr&eacute;venir les rechutes en cas de r&eacute;cidives fr&eacute;quentes et &agrave; quels effets ind&eacute;sirables peut-on s&rsquo;attendre&nbsp;?<\/p>\n<p>Il n&#39;existe pratiquement aucune RCT sur le choix du v&eacute;hicule. Le <b>choix du v&eacute;hicule <\/b>sera d&eacute;termin&eacute; en fonction de la pr&eacute;sentation clinique. Face &agrave; un ecz&eacute;ma suintant&#x002C; le choix se porte sur un corticost&eacute;ro&iuml;de en cr&egrave;me ou en lotion. Face &agrave; un ecz&eacute;ma sec&#x002C; le choix se portera plut&ocirc;t sur un corticost&eacute;ro&iuml;de &agrave; base grasse (p.&nbsp;ex. pommade).<\/p>\n<p>Une r&eacute;cente revue <i>Cochrane<\/i> a examin&eacute; les autres questions qui se posent souvent au sujet du traitement par dermocortico&iuml;des<span class='folia-referentie-nummer'><sup>6<\/sup><\/span>. Dans cette revue&#x002C; les auteurs ont r&eacute;sum&eacute; les r&eacute;sultats de plusieurs &eacute;tudes ayant compar&eacute; diff&eacute;rents sch&eacute;mas de traitement. L&#39;une des principales limites des &eacute;tudes incluses dans cette revue &eacute;tait la dur&eacute;e souvent tr&egrave;s courte (entre 1 et 6 semaines). Des &eacute;tudes de courte dur&eacute;e sont mal con&ccedil;ues pour &eacute;valuer l&rsquo;efficacit&eacute; d&rsquo;un traitement chronique comme celui qui est requis dans l&rsquo;ecz&eacute;ma atopique.<\/p>\n<div class='detailed-content'>Au total&#x002C; la revue a inclus 104&nbsp;&eacute;tudes randomis&eacute;es&#x002C; repr&eacute;sentant un total de 8&nbsp;433&nbsp;patients. La majorit&eacute; des &eacute;tudes ont &eacute;t&eacute; men&eacute;es en milieu hospitalier et dans des pays &agrave; revenu &eacute;lev&eacute;. Il s&rsquo;agissait surtout d&rsquo;&eacute;tudes &agrave; court terme (dur&eacute;e comprise entre 1 et 6&nbsp;semaines). Les &eacute;tudes ayant &eacute;valu&eacute; la pr&eacute;vention des rechutes duraient plus longtemps&#x002C; mais jamais plus de 6&nbsp;mois. L&rsquo;&acirc;ge des participants &eacute;tait variable&#x002C; 43&nbsp;&eacute;tudes n&rsquo;incluaient que des enfants. La gravit&eacute; de l&rsquo;ecz&eacute;ma a &eacute;t&eacute; jug&eacute;e mod&eacute;r&eacute;e ou s&eacute;v&egrave;re dans 51&nbsp;&eacute;tudes&#x002C; l&eacute;g&egrave;re &agrave; mod&eacute;r&eacute;e dans 16&nbsp;&eacute;tudes et l&eacute;g&egrave;re &agrave; s&eacute;v&egrave;re dans 3&nbsp;&eacute;tudes. Dans 34&nbsp;&eacute;tudes&#x002C; la gravit&eacute; de l&rsquo;ecz&eacute;ma n&rsquo;&eacute;tait pas rapport&eacute;e. Parmi les &eacute;tudes incluses&#x002C; aucune n&rsquo;a utilis&eacute; un traitement combin&eacute; (par exemple&#x002C; des corticost&eacute;ro&iuml;des associ&eacute;s &agrave; des antimycosiques ou des antibiotiques).<\/div>\n<h3>Puissance du corticost&eacute;ro&iuml;de<\/h3>\n<p>Les sp&eacute;cialit&eacute;s disponibles sont class&eacute;es en quatre cat&eacute;gories en fonction de leur puissance (tr&egrave;s puissantes&#x002C; puissantes&#x002C; moyennement puissantes et peu puissantes)&#x002C; qui d&eacute;pend de la nature de la mol&eacute;cule et de la concentration en principe actif. (<a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=14233'>voir R&eacute;pertoire 15.2 Corticost&eacute;ro&iuml;des<\/a>). En ce qui concerne les pr&eacute;parations magistrales&#x002C; voir le Formulaire <a href='https:\/\/www.tmf-ftm.be\/fr_FR\/web\/physician\/ftm\/d\/dii'>Th&eacute;rapeutique Magistral (TMF)<\/a> pour conna&icirc;tre les pr&eacute;parations disponibles et leurs concentrations maximales recommand&eacute;es.<\/p>\n<p>Pour le premier traitement&#x002C; le choix se porte g&eacute;n&eacute;ralement sur le corticost&eacute;ro&iuml;de le moins puissant estim&eacute; capable de r&eacute;primer les sympt&ocirc;mes (strat&eacute;gie <i>step up<\/i>). Lorsque les manifestations sont plus graves&#x002C; une pr&eacute;paration tr&egrave;s puissante est parfois initi&eacute;e d&rsquo;embl&eacute;e&#x002C; &agrave; laquelle on substitue ensuite une pr&eacute;paration moins puissante en cas de r&eacute;ponse favorable (strat&eacute;gie <i>step down<\/i>). Aucune RCT comparative de ces deux strat&eacute;gies n&rsquo;a pu &ecirc;tre trouv&eacute;e. La revue Cochrane n&rsquo;est donc pas en mesure de nous renseigner sur le profil d&rsquo;efficacit&eacute; et d&rsquo;innocuit&eacute; de ces strat&eacute;gies.<\/p>\n<p>La revue Cochrane conclut que&#x002C; dans l&rsquo;ecz&eacute;ma mod&eacute;r&eacute; &agrave; s&eacute;v&egrave;re&#x002C; les pr&eacute;parations puissantes et moyennement puissantes sont sup&eacute;rieures aux pr&eacute;parations peu puissantes. Par contre&#x002C; les pr&eacute;parations tr&egrave;s puissantes ne se sont pas r&eacute;v&eacute;l&eacute;es sup&eacute;rieures aux pr&eacute;parations puissantes.<\/p>\n<div class='detailed-content'>Pour le crit&egrave;re d&rsquo;&eacute;valuation &laquo;&nbsp;r&eacute;ponse compl&egrave;te ou partielle&nbsp;&raquo;&#x002C; les comparaisons suivantes ont &eacute;t&eacute; &eacute;valu&eacute;es: <\/p>\n<ul>\n<li>Pr&eacute;parations moyennement puissantes <i>versus<\/i> pr&eacute;parations peu puissantes :<br \/> Rapport de cotes (RC) 2&#x002C;07 (IC &agrave; 95% de 1&#x002C;41 &agrave; 3&#x002C;04) ; niveau de preuve mod&eacute;r&eacute; (statistiquement significatif)<\/li>\n<li>Pr&eacute;parations puissantes <i>versus<\/i> pr&eacute;parations peu puissantes&nbsp;: RC 3&#x002C;71 (IC &agrave; 95% de 2&#x002C;04 &agrave; 6&#x002C;72) ; niveau de preuve mod&eacute;r&eacute; (statistiquement significatif)<\/li>\n<li>Pr&eacute;parations puissantes <i>versus<\/i> pr&eacute;parations moyennement puissantes&nbsp;: RC 1&#x002C;33 (IC &agrave; 95% de 0&#x002C;93 &agrave; 1&#x002C;89); niveau de preuve mod&eacute;r&eacute; (statistiquement non significatif)<\/li>\n<li>Pr&eacute;parations tr&egrave;s puissantes <i>versus<\/i> pr&eacute;parations puissantes&nbsp;: RC 0&#x002C;53 (IC &agrave; 95% de 0&#x002C;13 &agrave; 2&#x002C;09) ; faible niveau de preuve (statistiquement non significatif)<\/li>\n<\/ul>\n<p> Note concernant les r&eacute;sultats des &eacute;tudes ayant compar&eacute; les pr&eacute;parations tr&egrave;s puissantes aux pr&eacute;parations puissantes&nbsp;: seules 3 &eacute;tudes de petite taille&#x002C; incluant principalement des enfants&#x002C; ont &eacute;t&eacute; examin&eacute;es pour cette analyse. Le niveau de preuve est donc faible.<\/p><\/div>\n<h3>Fr&eacute;quence d&rsquo;application du corticost&eacute;ro&iuml;de<\/h3>\n<p>Les r&eacute;sultats de la revue Cochrane confirment qu&rsquo;une seule application par jour de corticost&eacute;ro&iuml;des topiques suffit g&eacute;n&eacute;ralement pour obtenir une gu&eacute;rison compl&egrave;te ou une nette am&eacute;lioration des l&eacute;sions cutan&eacute;es.<\/p>\n<div class='detailed-content'>Pour le crit&egrave;re d&rsquo;&eacute;valuation &laquo;&nbsp;r&eacute;ponse compl&egrave;te ou partielle&nbsp;&raquo;&#x002C; la comparaison suivante a &eacute;t&eacute; &eacute;valu&eacute;e&nbsp;: <\/p>\n<ul>\n<li>Traitement 1 x par jour <i>versus<\/i> traitement 2 x par jour&nbsp;: RC 0&#x002C;97 (IC &agrave; 95% de 0&#x002C;68 de 1&#x002C;38).<\/li>\n<\/ul><\/div>\n<p>La strat&eacute;gie <i>step down<\/i> peut consister &agrave; diminuer la puissance de la pr&eacute;paration&#x002C; mais aussi &agrave; en r&eacute;duire progressivement la fr&eacute;quence d&rsquo;application. Il n&rsquo;existe aucune RCT sur cette strat&eacute;gie th&eacute;rapeutique. La revue Cochrane n&rsquo;est donc pas en mesure de nous renseigner &agrave; ce sujet.<\/p>\n<h3>Dur&eacute;e du traitement corticost&eacute;ro&iuml;de<\/h3>\n<p>Le traitement par corticost&eacute;ro&iuml;de doit &ecirc;tre poursuivi jusqu&rsquo;&agrave; la gu&eacute;rison compl&egrave;te ou l&rsquo;am&eacute;lioration manifeste des l&eacute;sions cutan&eacute;es. En cas de r&eacute;ponse insuffisante&#x002C; il faut d&rsquo;abord &eacute;valuer l&rsquo;observance th&eacute;rapeutique et la prise en charge de possibles facteurs aggravants&#x002C; notamment une allergie au corticost&eacute;ro&iuml;de. Dans un deuxi&egrave;me temps&#x002C; le corticost&eacute;ro&iuml;de choisi peut &eacute;ventuellement &ecirc;tre remplac&eacute; par une pr&eacute;paration plus puissante. Le guideline du NHG sur l&rsquo;ecz&eacute;ma recommande de r&eacute;&eacute;valuer le traitement apr&egrave;s 1 &agrave; 2&nbsp;semaines<span class='folia-referentie-nummer'><sup>1<\/sup><\/span>.<\/p>\n<h3>Traitement proactif (pr&eacute;vention des rechutes)<\/h3>\n<p>Un traitement proactif consiste &agrave; appliquer un dermocortico&iuml;de deux fois par semaine&#x002C; en une seule application quotidienne&#x002C; pendant deux jours cons&eacute;cutifs (&laquo;&nbsp;traitement de fin de semaine&nbsp;&raquo;). Ce traitement vise &agrave; pr&eacute;venir les rechutes chez les patients pr&eacute;sentant des r&eacute;cidives tr&egrave;s fr&eacute;quentes.<\/p>\n<p>D&rsquo;apr&egrave;s la revue Cochrane&#x002C; le traitement proactif entra&icirc;ne une diminution substantielle du risque de rechute&#x002C; tant chez l&rsquo;adulte que chez l&rsquo;enfant&#x002C; et quel que soit le degr&eacute; d&rsquo;ecz&eacute;ma atopique (niveau de preuve mod&eacute;r&eacute;).<\/p>\n<div class='detailed-content'>Le traitement proactif a r&eacute;duit le risque de rechute de 58% &agrave; 25% (niveau de preuve mod&eacute;r&eacute;)&nbsp;: RC de 0&#x002C;43 (IC &agrave; 95% de 0&#x002C;32 &agrave; 0&#x002C;57) (statistiquement significatif).<\/div>\n<h3>Donn&eacute;es de s&eacute;curit&eacute;<\/h3>\n<p>Les dermocortico&iuml;des sont connus pour &ecirc;tre susceptibles de provoquer divers effets ind&eacute;sirables locaux et syst&eacute;miques. Les effets ind&eacute;sirables locaux et syst&eacute;miques (<a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=14233'>voir R&eacute;pertoire 15.2.<\/a><a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=14233'> Corticost&eacute;ro&iuml;des<\/a> &gt; rubriques Effets ind&eacute;sirables et Pr&eacute;cautions particuli&egrave;res) d&eacute;pendent du cortico&iuml;de: de sa concentration et de sa puissance&#x002C; du v&eacute;hicule (une pommade est en g&eacute;n&eacute;ral plus absorb&eacute;e qu&rsquo;une cr&egrave;me ou une lotion)&#x002C; de la dur&eacute;e du traitement. D&rsquo;autres facteurs entrent en ligne de compte&nbsp;: &nbsp;l&rsquo;&eacute;tat de la peau mais aussi la nature de l&rsquo;affection trait&eacute;e&#x002C; sa localisation (p.&nbsp;ex. plut&ocirc;t au niveau du visage ou des organes g&eacute;nitaux) et son &eacute;tendue&#x002C; ainsi que l&rsquo;&acirc;ge du patient. L&rsquo;utilisation de fortes doses ou de pr&eacute;parations puissantes &agrave; tr&egrave;s puissantes&#x002C; et l&#39;application sur une peau l&eacute;s&eacute;e ou sous un pansement occlusif&#x002C; expose &agrave; un risque accru d&#39;effets ind&eacute;sirables.<\/p>\n<div class='detailed-content'>Les corticost&eacute;ro&iuml;des sont associ&eacute;s &agrave; des effets ind&eacute;sirables locaux&#x002C; en particulier avec les pr&eacute;parations puissantes &agrave; tr&egrave;s puissantes. Les principaux effets ind&eacute;sirables observ&eacute;s sont&nbsp;: atrophie cutan&eacute;e&#x002C; vergetures&#x002C; t&eacute;langiectasies&#x002C; infections&#x002C; et dermatite p&eacute;riorale.<\/p>\n<p> Les &eacute;tudes r&eacute;v&egrave;lent que les pr&eacute;parations puissantes &agrave; tr&egrave;s puissantes peuvent influencer le taux de cortisol&#x002C; mais la pertinence clinique de cet effet est incertaine. Il existe trop peu d&rsquo;&eacute;tudes pour &eacute;valuer l&rsquo;effet des corticost&eacute;ro&iuml;des sur la densit&eacute; osseuse&#x002C; le glaucome et la croissance. Il n&rsquo;existe pas de donn&eacute;es probantes concernant la survenue d&rsquo;effets ind&eacute;sirables syst&eacute;miques lors de l&rsquo;utilisation de pr&eacute;parations peu &agrave; moyennement puissantes<span class='folia-referentie-nummer'><sup>1<\/sup><\/span>.<\/div>\n<p>Les &eacute;tudes discut&eacute;es dans la revue Cochrane ne permettent pas d&rsquo;&eacute;valuer la s&eacute;curit&eacute; &agrave; long terme d&rsquo;un traitement topique par corticost&eacute;ro&iuml;des chez l&rsquo;enfant et l&rsquo;adulte&#x002C; en raison de la courte dur&eacute;e des &eacute;tudes et de la notification insuffisante des effets ind&eacute;sirables. Les &eacute;tudes n&rsquo;ont pas rapport&eacute; d&rsquo;augmentation du nombre d&rsquo;effets ind&eacute;sirables en fonction de la puissance du corticost&eacute;ro&iuml;de ni de la fr&eacute;quence d&rsquo;application.<\/p>\n<div class='detailed-content'>La plupart des &eacute;tudes incluses duraient entre 1 et 5&nbsp;semaines&#x002C; sans suivi apr&egrave;s le traitement. Il est donc difficile de d&eacute;tecter les effets ind&eacute;sirables tels qu&rsquo;une atrophie cutan&eacute;e ou une hypopigmentation&#x002C; qui mettent souvent des mois&#x002C; voire des ann&eacute;es&#x002C; &agrave; se d&eacute;velopper.<\/p>\n<p> Les &eacute;tudes ayant &eacute;valu&eacute; l&rsquo;efficacit&eacute; d&rsquo;un traitement proactif duraient souvent plus longtemps. Aucun cas d&#39;effets locaux tels qu&rsquo;une atrophie cutan&eacute;e n&#39;a &eacute;t&eacute; constat&eacute; dans ces &eacute;tudes. La dose hebdomadaire de corticost&eacute;ro&iuml;des utilis&eacute;e dans ces &eacute;tudes est inf&eacute;rieure aux doses utilis&eacute;es dans le traitement de l&rsquo;ecz&eacute;ma. Les donn&eacute;es de s&eacute;curit&eacute; ne peuvent donc pas &ecirc;tre extrapol&eacute;es aux doses plus &eacute;lev&eacute;es de corticost&eacute;ro&iuml;des qui sont utilis&eacute;es dans le traitement de l&rsquo;ecz&eacute;ma.<\/p><\/div>\n<p>En ce qui concerne l&#39;utilisation pendant la grossesse&#x002C; des effets ind&eacute;sirables ne sont attendus qu&#39;en cas d&#39;utilisation de doses &eacute;lev&eacute;es ou de pr&eacute;parations puissantes &agrave; tr&egrave;s puissantes&#x002C; en cas d&rsquo;application sur une peau l&eacute;s&eacute;e.<\/p>\n<div class='detailed-content'>Pour la plupart des m&eacute;dicaments appliqu&eacute;s localement&#x002C; le risque de probl&egrave;mes pendant <b>la grossesse et la p&eacute;riode d&rsquo;allaitement<\/b> est r&eacute;duit vu la faible absorption syst&eacute;mique. Dans les conditions normales d&rsquo;utilisation&#x002C; aucun effet n&eacute;gatif n&rsquo;est &agrave; pr&eacute;voir sur la grossesse ou l&rsquo;enfant &agrave; na&icirc;tre. Les donn&eacute;es les plus rassurantes concernant l&rsquo;utilisation de ces pr&eacute;parations pendant la grossesse sont celles li&eacute;es aux pr&eacute;parations peu &agrave; moyennement puissantes<span class='folia-referentie-nummer'><sup>6&#x002C;7<\/sup><\/span>. En cas d&rsquo;utilisation de fortes doses ou de pr&eacute;parations puissantes &agrave; tr&egrave;s puissantes&#x002C; en cas d&rsquo;application sur une peau l&eacute;s&eacute;e ou sous un pansement occlusif&#x002C; des effets ind&eacute;sirables tels qu&#39;un faible poids de naissance et une insuffisance surr&eacute;nalienne peuvent se produire chez le f&oelig;tus et le nouveau-n&eacute;<span class='folia-referentie-nummer'><sup>7&#x002C;8<\/sup><\/span>.<\/div>\n<h2>Les immunomodulateurs topiques<\/h2>\n<p>Le pim&eacute;crolimus et le tacrolimus&#x002C; deux inhibiteurs de la calcineurine&#x002C; sont des immunomodulateurs et constituent des alternatives possibles aux dermocortico&iuml;des dans le traitement de fond de l&rsquo;ecz&eacute;ma en cas d&rsquo;intol&eacute;rance&#x002C; de contre-indication ou d&rsquo;inefficacit&eacute; des dermocortico&iuml;des. L&rsquo;all&eacute;gation selon laquelle une application sur le visage aurait une valeur ajout&eacute;e&#x002C; n&#39;est pas &eacute;tay&eacute;e par des &eacute;tudes comparatives.<\/p>\n<p>Dans une revue Cochrane de 2015 ayant compar&eacute; l&rsquo;efficacit&eacute; d&rsquo;un traitement par tacrolimus topique avec d&rsquo;autres traitements actifs dans la dermatite atopique&#x002C; le tacrolimus 1&nbsp;% ne s&rsquo;est pas r&eacute;v&eacute;l&eacute; sup&eacute;rieur aux pr&eacute;parations de corticost&eacute;ro&iuml;des moyennement puissantes &agrave; puissantes (faible niveau de preuve)<span class='folia-referentie-nummer'><sup>9<\/sup><\/span>.<\/p>\n<p>Dans une synth&egrave;se m&eacute;thodique de 2016&#x002C; les inhibiteurs de la calcineurine topiques (pim&eacute;crolimus et tacrolimus) et les corticost&eacute;ro&iuml;des avaient une efficacit&eacute; similaire&#x002C; mais le traitement par inhibiteurs de la calcineurine &eacute;tait toutefois associ&eacute; &agrave; davantage d&rsquo;effets ind&eacute;sirables locaux&#x002C; tels que prurit et sensation de br&ucirc;lure sur la peau&#x002C; de m&ecirc;me qu&rsquo;&agrave; un co&ucirc;t plus &eacute;lev&eacute;. Aucune diff&eacute;rence n&rsquo;a &eacute;t&eacute; observ&eacute;e en termes d&rsquo;atrophie cutan&eacute;e&#x002C; d&rsquo;infections cutan&eacute;es ou d&rsquo;effets ind&eacute;sirables graves ayant n&eacute;cessit&eacute; l&rsquo;arr&ecirc;t du traitement<span class='folia-referentie-nummer'><sup>10<\/sup><\/span>.<\/p>\n<div class='detailed-content'>Analyse de 12&nbsp;RCT ayant compar&eacute; des immunomodulateurs (n=3&nbsp;492) &agrave; des corticost&eacute;ro&iuml;des (n=3&nbsp;462). La dur&eacute;e des &eacute;tudes variait de 2&nbsp;semaines &agrave; 6&nbsp;mois. La gravit&eacute; de l&rsquo;ecz&eacute;ma variait de mod&eacute;r&eacute;e &agrave; s&eacute;v&egrave;re. L&rsquo;utilisation d&rsquo;immunomodulateurs <i>vs<\/i> corticost&eacute;ro&iuml;des a r&eacute;sult&eacute; en pourcentages comparables d&rsquo;am&eacute;lioration de l&rsquo;ecz&eacute;ma (81% <i>vs<\/i> 71%&nbsp;; risque relatif de 1&#x002C;18&nbsp;; IC &agrave; 95% de 1&#x002C;04 &agrave; 1&#x002C;34&nbsp;; p=0&#x002C;01) et de r&eacute;ussite du traitement (72% <i>vs<\/i> 68%&nbsp;; risque relatif de 1&#x002C;15&nbsp;; IC &agrave; 95% de 1&#x002C;00 &agrave; 1&#x002C;31&nbsp;; p=0&#x002C;04).<\/p>\n<p> Les immunomodulateurs &eacute;taient associ&eacute;s &agrave; davantage d&rsquo;effets ind&eacute;sirables (74% <i>vs<\/i> 64%&nbsp;; risque relatif de 1&#x002C;28&nbsp;; IC &agrave; 95% de 1&#x002C;05 &agrave; 1&#x002C;58&nbsp;; p=0&#x002C;02)&#x002C; surtout &agrave; un pourcentage plus &eacute;lev&eacute; de personnes pr&eacute;sentant une sensation de br&ucirc;lure (30% <i>vs<\/i> 9%&nbsp;; risque relatif de 3&#x002C;27&nbsp;; IC &agrave; 95% de 2&#x002C;48 &agrave; 4&#x002C;13&nbsp;; p=0&#x002C;00001) et un prurit (12% <i>vs<\/i> 8%&nbsp;; risque relatif de 1&#x002C;49&nbsp;; IC &agrave; 95% de 1&#x002C;24 &agrave; 1&#x002C;79&nbsp;; p=0&#x002C;00001). Aucune diff&eacute;rence n&rsquo;a &eacute;t&eacute; observ&eacute;e en termes d&rsquo;atrophie cutan&eacute;e&#x002C; d&rsquo;infections cutan&eacute;es ou d&rsquo;effets ind&eacute;sirables graves ayant n&eacute;cessit&eacute; l&rsquo;arr&ecirc;t du traitement. La courte dur&eacute;e de la plupart des &eacute;tudes ne permet pas d&rsquo;&eacute;valuer la s&eacute;curit&eacute; des produits &agrave; long terme. &nbsp;<\/p>\n<p> Notons aussi que le co&ucirc;t d&rsquo;un traitement par immunomodulateurs est nettement plus &eacute;lev&eacute; que celui d&rsquo;un traitement par corticost&eacute;ro&iuml;des.<\/p><\/div>\n<p>La question de savoir si l&#39;utilisation d&#39;immunomodulateurs est associ&eacute;e ou non &agrave; un risque accru de malignit&eacute;s fait depuis longtemps l&#39;objet d&#39;un d&eacute;bat<span class='folia-referentie-nummer'><sup>11<\/sup><\/span>. Davantage d&rsquo;&eacute;tudes &agrave; long terme sont n&eacute;cessaires pour d&eacute;terminer le risque canc&eacute;rog&egrave;ne&#x002C; mais la plupart des donn&eacute;es r&eacute;centes sont rassurantes.<\/p>\n<div class='detailed-content'>En 2005&#x002C; la <i>Food and Drug Administration<\/i> (FDA) am&eacute;ricaine a introduit un &laquo;&nbsp;boxed warning&nbsp;&raquo; (avertissement encadr&eacute;) pour les immunomodulateurs topiques (pim&eacute;crolimus et tacrolimus). En effet&#x002C; plusieurs &eacute;tudes animales avaient &eacute;tabli une incidence accrue de tumeurs malignes lors de la prise de ces produits. En d&eacute;cembre 2004&#x002C; la FDA avait re&ccedil;u 19&nbsp;notifications de cas de patients atteints de lymphomes ou de cancers cutan&eacute;s qui avaient &eacute;t&eacute; trait&eacute;s avec du tacrolimus topique. &Agrave; la m&ecirc;me date&#x002C; la FDA avait &eacute;galement re&ccedil;u 10 notifications de cas de pathologies malignes chez des patients trait&eacute;s avec du pim&eacute;crolimus topique.<\/p>\n<p> Dans la litt&eacute;rature&#x002C; certaines &eacute;tudes montrent une association entre l&rsquo;utilisation topique des immunomodulateurs (tacrolimus et pim&eacute;crolimus) et un risque accru de lymphomes&#x002C; mais cette association n&rsquo;a pas &eacute;t&eacute; trouv&eacute;e dans d&rsquo;autres &eacute;tudes<span class='folia-referentie-nummer'><sup>12&#x002C;13&#x002C;14&#x002C;15&#x002C;16<\/sup><\/span>.<\/div>\n<p>Il n&#39;est pas possible de se prononcer sur la s&eacute;curit&eacute; d&rsquo;emploi des immunomodulateurs topiques pendant la grossesse (absence de donn&eacute;es ou donn&eacute;es insuffisantes)<span class='folia-referentie-nummer'><sup>17<\/sup><\/span>.<\/p>\n<div class='detailed-content'>L&#39;utilisation d&#39;immunomodulateurs topiques pendant la grossesse n&rsquo;est pas document&eacute;e. D&#39;apr&egrave;s les &eacute;tudes men&eacute;es chez les femmes non enceintes&#x002C; les immunomodulateurs topiques sont tr&egrave;s peu absorb&eacute;s par la peau intacte et peuvent &ecirc;tre utilis&eacute;s de mani&egrave;re limit&eacute;e pendant la grossesse.<\/div>\n<h2>Conclusion<\/h2>\n<ul>\n<li>\n<p>L&#39;ecz&eacute;ma atopique est une maladie inflammatoire chronique de la peau qui implique souvent des facteurs d&eacute;clenchants &eacute;vitables. Il est important d&rsquo;en tenir compte.<\/p>\n<\/li>\n<li>\n<p>Le traitement local reste la pierre angulaire pour toutes les formes d&#39;ecz&eacute;ma atopique. Les formes tr&egrave;s s&eacute;v&egrave;res peuvent justifier le recours &agrave; un traitement par immunomodulateurs syst&eacute;miques (tels que certains inhibiteurs d&#39;interleukine ou de Janus kinase) ou &agrave; une phototh&eacute;rapie.<\/p>\n<\/li>\n<li>\n<p>Les &eacute;mollients font toujours partie du traitement de base de l&rsquo;ecz&eacute;ma et s&rsquo;utilisent de pr&eacute;f&eacute;rence en permanence&#x002C; y compris apr&egrave;s la r&eacute;solution des l&eacute;sions ecz&eacute;mateuses.<\/p>\n<\/li>\n<li>\n<p>La revue Cochrane sur les dermocortico&iuml;des dans l&rsquo;ecz&eacute;ma conclut ce qui suit&nbsp;:<\/p>\n<ul>\n<li>\n<p>Dans l&#39;ecz&eacute;ma mod&eacute;r&eacute; &agrave; s&eacute;v&egrave;re&#x002C; l&rsquo;efficacit&eacute; des pr&eacute;parations moyennement puissantes et puissantes est sup&eacute;rieure &agrave; celle des pr&eacute;parations peu puissantes&#x002C; et similaire &agrave; celle des pr&eacute;parations tr&egrave;s puissantes. Une seule application par jour est aussi efficace qu&rsquo;une application deux fois par jour.<\/p>\n<\/li>\n<li>\n<p>Un traitement proactif peut &ecirc;tre utilis&eacute; pour pr&eacute;venir les rechutes chez les personnes pr&eacute;sentant de fr&eacute;quentes r&eacute;cidives.<\/p>\n<\/li>\n<li>\n<p>Les donn&eacute;es sur la s&eacute;curit&eacute; et l&#39;efficacit&eacute; &agrave; long terme des corticost&eacute;ro&iuml;des en application locale restent insuffisantes.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p>Les immunomodulateurs&#x002C; le tacrolimus et le pim&eacute;crolimus&#x002C; ont une place en cas d&rsquo;intol&eacute;rance aux dermocortico&iuml;des. Les immunomodulateurs ne se sont pas r&eacute;v&eacute;l&eacute;s sup&eacute;rieurs aux corticost&eacute;ro&iuml;des dans le traitement de l&rsquo;ecz&eacute;ma atopique. Ils sont associ&eacute;s &agrave; un risque accru d&#39;effets ind&eacute;sirables locaux (mineurs) sans qu&#39;il y ait de preuves claires d&#39;une r&eacute;duction du risque d&#39;atrophie cutan&eacute;e. Certaines &eacute;tudes ont observ&eacute; un risque l&eacute;g&egrave;rement major&eacute; de cancers cutan&eacute;s et de lymphomes&#x002C; mais cette observation reste controvers&eacute;e. Les immunomodulateurs ont un co&ucirc;t nettement plus &eacute;lev&eacute;.<\/p>\n<\/li>\n<\/ul>\n<h2> Sources<\/h2>\n<p><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1&nbsp;<\/span>Nederlands Huisartsen Genootschap (NHG). NHG-Standaard eczeem. Mei 2014. Via <a href='https:\/\/richtlijnen.nhg.org\/standaarden\/eczeem'>https:\/\/richtlijnen.nhg.org\/standaarden\/eczeem<\/a><\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>2&nbsp;<\/span>Wolkerstorfer A&#x002C; de Waard van der Spek FB&#x002C; Glazenburg EJ&#x002C; Mulder PG&#x002C; Oranje AP. Scoring the severity of atopic dermatitis: three item severity score as a rough system for daily practice and as a pre-screening tool for studies. Acta Derm Venereol. 1999;79(5):356-359. doi:10.1080\/000155599750010256<br \/> <span class='folia-referentie-nummer'>3<\/span>&nbsp;NICE Atopic eczema in under 12s: diagnosis and management <a href='https:\/\/www.guidelines.co.uk\/skin-and-wound-care\/nice-eczema-in-under-12s-guideline\/207625.article'>https:\/\/www.guidelines.co.uk\/skin-and-wound-care\/nice-eczema-in-under-12s-guideline\/207625.article<\/a><br \/> <span class='folia-referentie-nummer'>4<\/span>&nbsp;van Zuuren EJ&#x002C; Fedorowicz Z&#x002C; Christensen R&#x002C; Lavrijsen A&#x002C; Arents BWM. Emollients and moisturisers for eczema. Cochrane Database Syst Rev. 2017;2(2):CD012119. Published 2017 Feb 6. doi:10.1002\/14651858.CD012119.pub2<br \/> <span class='folia-referentie-nummer'>5<\/span>&nbsp;Chaoimh CN&#x002C; Lad D&#x002C; Nico C&#x002C; et al. Early initiation of short-term emollient use for the prevention of atopic dermatitis in high-risk infants&mdash;The STOP-AD randomised controlled trial. <i>Allergy<\/i>. n\/a(n\/a). doi:<a href='https:\/\/doi.org\/10.1111\/all.15491'>10.1111\/all.15491<\/a><\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>6<\/span>&nbsp;Lax SJ&#x002C; HarveyJ&#x002C; AxonE&#x002C; HowellsL&#x002C; SanterM&#x002C; RiddMJ&#x002C; LawtonS&#x002C; LanganS&#x002C; RobertsA&#x002C; AhmedA&#x002C; MullerI&#x002C; MingLC&#x002C; PandaS&#x002C; ChernyshovP&#x002C; CarterB&#x002C; WilliamsHC&#x002C; ThomasKS&#x002C; ChalmersJR.Strategies for using topical corticosteroids in children and adults with eczema. Cochrane Database of Systematic Reviews 2022&#x002C; Issue 3. Art. No.: CD013356. DOI: 10.1002\/14651858.CD013356.pub2.<br \/> <span class='folia-referentie-nummer'>7<\/span>&nbsp;Lareb. Corticostero&iuml;den op de huid tijdens de zwangerschap. Consult&eacute; le 20 septembre 2022. <a href='https:\/\/www.lareb.nl\/mvm-kennis'>Site Web Lareb<\/a>.<br \/> <span class='folia-referentie-nummer'>8<\/span>&nbsp;Centre de r&eacute;f&eacute;rence sur les Agents t&eacute;ratog&egrave;nes. Centre de r&eacute;f&eacute;rence sur les Agents t&eacute;ratog&egrave;nes. Consult&eacute; le 20 septembre 2022. <a href='https:\/\/www.lecrat.fr\/'>Site Web Le CRAT<\/a>.<br \/> <span class='folia-referentie-nummer'>9<\/span>&nbsp;Cury Martins J&#x002C; Martins C&#x002C; Aoki V&#x002C; Gois AFT&#x002C; Ishii HA&#x002C; da Silva EMK. Topical tacrolimus for atopic dermatitis. Cochrane Database of Systematic Reviews 2015&#x002C; Issue 7. Art. No.: CD009864. DOI: 10.1002\/14651858.CD009864.pub2. Accessed 11 August 2022.<br \/> <span class='folia-referentie-nummer'>10<\/span>&nbsp;Broeders JA&#x002C; Ahmed Ali U&#x002C; Fischer G. Systematic review and meta-analysis of randomized clinical trials (RCTs) comparing topical calcineurin inhibitors with topical corticosteroids for atopic dermatitis: A 15-year experience. J Am Acad Dermatol. 2016;75(2):410-419.e3. doi:10.1016\/j.jaad.2016.02.1228<br \/> <span class='folia-referentie-nummer'>11<\/span>Martindale. The complete drug reference. Consult&eacute; le 22 septembre 2022.<br \/> <span class='folia-referentie-nummer'>12<\/span>&nbsp;Lam M&#x002C; Zhu JW&#x002C; Tadrous M&#x002C; Drucker AM. Association Between Topical Calcineurin Inhibitor Use and Risk of Cancer&#x002C; Including Lymphoma&#x002C; Keratinocyte Carcinoma&#x002C; and Melanoma: A Systematic Review and Meta-analysis. JAMA Dermatol. 2021;157(5):549-558. doi:10.1001\/jamadermatol.2021.0345<br \/> <span class='folia-referentie-nummer'>13<\/span>&nbsp;Wu PC&#x002C; Huang IH&#x002C; Liu CW&#x002C; Huang YC. Topical calcineurin inhibitors and risk of lymphoma: a systematic review and meta-analysis. J Dtsch Dermatol Ges. 2021;19(9):1265-1269. doi:10.1111\/ddg.14527<br \/> <span class='folia-referentie-nummer'>14<\/span>&nbsp;Paller AS&#x002C; F&ouml;lster-Holst R&#x002C; Chen SC&#x002C; et al. No evidence of increased cancer incidence in children using topical tacrolimus for atopic dermatitis. J Am Acad Dermatol. 2020;83(2):375-381. doi:10.1016\/j.jaad.2020.03.075<br \/> <span class='folia-referentie-nummer'>15<\/span>&nbsp;Arana A&#x002C; Potteg&aring;rd A&#x002C; Kuiper JG&#x002C; et al. Long-Term Risk of Skin Cancer and Lymphoma in Users of Topical Tacrolimus and Pimecrolimus: Final Results from the Extension of the Cohort Study Protopic Joint European Longitudinal Lymphoma and Skin Cancer Evaluation (JOELLE). Clin Epidemiol. 2021;13:1141-1153. Published 2021 Dec 29. doi:10.2147\/CLEP.S331287<br \/> <span class='folia-referentie-nummer'>16<\/span>&nbsp;Devasenapathy N&#x002C; Chu A&#x002C; Wong M&#x002C; Srivastava A&#x002C; Ceccacci R&#x002C; Lin C&#x002C; et al. Cancer risk with topical calcineurin inhibitors&#x002C; pimecrolimus and tacrolimus&#x002C; for atopic dermatitis: a systematic review and meta-analysis. The Lancet Child &amp; Adolescent Health 2022;0. <a href='https:\/\/doi.org\/10.1016\/S2352-4642(22)00283-8'>https:\/\/doi.org\/10.1016\/S2352-4642(22)00283-8<\/a>.<br \/> <span class='folia-referentie-nummer'>17<\/span>&nbsp;Lareb. Lokale middelen voor seborroisch of moeilijk te behandelen eczeem tijdens de zwangerschap Consult&eacute; le 3 janvier 2023. <a href='https:\/\/www.lareb.nl\/mvm-kennis-pagina?id=162&amp;pagina=1'>Site Web Lareb<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ecz&eacute;ma atopique se traite avant tout localement&#x002C; avec une combinaison  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-186626","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186626"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186626\/revisions"}],"predecessor-version":[{"id":189183,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186626\/revisions\/189183"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}