{"id":186592,"date":"2023-05-02T00:00:00","date_gmt":"2023-05-01T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/nouveautes-medicaments-avril-2023\/"},"modified":"2026-07-09T15:11:59","modified_gmt":"2026-07-09T13:11:59","slug":"nouveautes-medicaments-avril-2023","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/nouveautes-medicaments-avril-2023\/","title":{"rendered":"Nouveaut\u00e9s m\u00e9dicaments avril 2023"},"content":{"rendered":"<div class='summary'><span class='new-molecules-small'>&nbsp;<\/span><span class='folia-samenvatting-vet'>Nouveaut&eacute;s en m&eacute;decine sp&eacute;cialis&eacute;e<\/span><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#ani'>anifrolumab (Saphnelo&reg;\u25bc):&nbsp;lupus &eacute;ryth&eacute;mateux syst&eacute;mique<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#ibu'>ibuprof&egrave;ne + parac&eacute;tamol IV (Combogesic&reg;<span class='mp-kidney-m'> <\/span>):&nbsp;douleur mod&eacute;r&eacute;e aigu&euml;<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp; &bull; <a href='#peg'>pegc&eacute;tacoplan (Aspaveli&reg;\u25bc<span class='ot'> <\/span>): h&eacute;moglobinurie paroxystique nocturne<\/a><\/span><\/span><br \/> <span class='folia-samenvatting-tekst'><span class='removed-molecules-small'>&nbsp;<\/span><span class='folia-samenvatting-vet'><b>Arr&ecirc;ts de commercialisation<\/b><\/span><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#ace'>acide ac&eacute;tylsalicylique + caf&eacute;ine (Aspirine Cafeine&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#dis'>disulfirame (Antabuse&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#ery'>&eacute;rythromycine + benzoyle peroxyde &agrave; usage cutan&eacute; (Benzadermine&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#fro'>frovatriptan (Migard&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'><span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#sel'>sulfure de s&eacute;l&eacute;nium (Selsun&reg;)<\/a><\/span><\/span><\/span><\/span><\/span><\/span><\/span><br \/> <span class='folia-samenvatting-tekst'><span class='removed-molecules-small'>&nbsp;<\/span><span class='folia-samenvatting-vet'><b>Interruptions de commercialisation<\/b><\/span><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#naf'>naftazone (Mediaven&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#som'>somatostatine (Somatostatine-Belpharma&reg; et Somatostatine-Eumedica&reg;)<\/a><br \/> <span class='folia-samenvatting-tekst'>&nbsp; &nbsp;&nbsp;&bull; <a href='#uro'>urokinase (Actosolv&reg;)<\/a><span class='folia-samenvatting-tekst'><br \/> <span class='folia-samenvatting-tekst'><span class='folia-samenvatting-tekst'><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/div>\n<div class='summary'><span class='folia-samenvatting-tekst'>\u25bc: <\/span>m&eacute;dicaments soumis &agrave; une surveillance particuli&egrave;re et pour lesquels la <a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>notification d<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>&rsquo;<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>effets ind<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>&eacute;<\/a><a href='https:\/\/www.afmps.be\/fr\/notifier_un_effet_indesirable_en_tant_que_professionnel_de_la_sante'>sirables<\/a> au Centre Belge de Pharmacovigilance est encourag&eacute;e (entre autres m&eacute;dicaments contenant un nouveau principe actif&#x002C; m&eacute;dicaments biologiques).<br \/> <span class='ot'>&nbsp;<\/span> : m&eacute;dicaments pour lesquels des proc&eacute;dures additionnelles de minimisation des risques (<i>Risk Minimization Activities<\/i>&nbsp;: RMA) ont &eacute;t&eacute; impos&eacute;es par l&rsquo;autorit&eacute; qui d&eacute;livre l&rsquo;autorisation de mise sur le march&eacute; (voir <a href='https:\/\/www.cbip.be\/fr\/articles\/2307?folia=2260'>Folia mars 2015<\/a>)&#x002C; telles que du mat&eacute;riel &eacute;ducatif ou des brochures.<br \/> <span class='mp-kidney-s'> <\/span> contre-indication ou r&eacute;duction de dose en cas d&rsquo;insuffisance r&eacute;nale s&eacute;v&egrave;re (clairance de la cr&eacute;atinine entre 30 et 15 ml\/min).<br \/> <span class='mp-kidney-m'> <\/span> contre-indication ou r&eacute;duction de dose d&eacute;j&agrave; en cas d&rsquo;insuffisance r&eacute;nale mod&eacute;r&eacute;e (clairance de la cr&eacute;atinine inf&eacute;rieure ou &eacute;gale &agrave; 60 ml\/min).<\/div>\n<p>Les actualit&eacute;s m&eacute;dicamenteuses de ce mois d&#39;avril prennent en compte les changements port&eacute;s &agrave; notre connaissance jusqu&rsquo;au 31 mars. Les modifications&nbsp; signal&eacute;es apr&egrave;s cette date seront reprises dans les Weekly Folia du mois de mai.<br \/> &nbsp;<br \/> Les textes du R&eacute;pertoire concernant ces actualit&eacute;s seront mis &agrave; jour &agrave; la date du 21 avril.<br \/> &nbsp;<\/p>\n<h2><a class='section' id='new-molecules-small'><span class='new-molecules-small'>&nbsp;<\/span><\/a>Nouveaut&eacute;s en m&eacute;decine sp&eacute;cialis&eacute;e<\/h2>\n<h3><a data-type='molecule' id='ani' name='ani'><\/a>anifrolumab (Saphnelo&reg;\u25bc)<\/h3>\n<div class='summary'><b>L&rsquo;anifrolumab <\/b>(<b>Saphnelo&reg;<\/b>\u25bc&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8903916'>chapitre 12.3.2.6.2<\/a>&#x002C; <b>administration intraveineuse<\/b>&#x002C; usage hospitalier) est un <b>anticorps monoclonal<\/b> anti IgG1 kappa antagoniste des r&eacute;cepteurs &agrave; l&rsquo;interf&eacute;ron de type I. Il a pour indication le <b>traitement additionnel du lupus &eacute;ryth&eacute;mateux syst&eacute;mique<\/b> (LES&#x002C; ou lupus &eacute;ryth&eacute;mateux diss&eacute;min&eacute; LED) mod&eacute;r&eacute; &agrave; s&eacute;v&egrave;re actif malgr&eacute; un traitement standard (synth&egrave;se du RCP). Il s&rsquo;agit du 2<sup>&egrave;me<\/sup> anticorps monoclonal autoris&eacute; dans cette indication (le 1<sup>er<\/sup> &eacute;tant le belimumab).<br \/> L&rsquo;anifrolumab a &eacute;t&eacute; &eacute;valu&eacute; versus placebo en traitement additionnel chez des patients atteints de formes mod&eacute;r&eacute;es &agrave; s&eacute;v&egrave;res de LES malgr&eacute; un traitement standard. Les <b>r&eacute;sultats<\/b> sur la r&eacute;ponse clinique ne sont <b>pas univoques<\/b>. Il n&rsquo;a <b>pas<\/b> &eacute;t&eacute; <b>&eacute;valu&eacute; par rapport &agrave; d&rsquo;autres traitements<\/b>&#x002C; ni chez des patients pr&eacute;sentant des atteintes neurologiques ou r&eacute;nales s&eacute;v&egrave;res. Son efficacit&eacute; sur la qualit&eacute; de vie ou en pr&eacute;vention des pouss&eacute;es n&rsquo;est pas connue. Il expose principalement &agrave; un <b>risque infectieux<\/b> (dont le <b>zona<\/b>)&#x002C; et des <b>r&eacute;actions li&eacute;es &agrave; la perfusion<\/b>.<span class='folia-referentie-note'>1-8<\/span><\/div>\n<div class='detailed-content'><b>Innocuit&eacute;<\/b><br \/> <u>Effets ind&eacute;sirables<\/u> <\/p>\n<ul>\n<li>Les plus fr&eacute;quents&nbsp;: infections des voies respiratoires sup&eacute;rieures et bronchite (&gt;10%)&#x002C; r&eacute;action li&eacute;e &agrave; la perfusion (9%) et zona (6%).<u> <\/u><\/li>\n<\/ul>\n<p> <u>Grossesse et allaitement<\/u> <\/p>\n<ul>\n<li>Selon le RCP&#x002C; l&rsquo;administration pendant la grossesse n&rsquo;est pas recommand&eacute;e&#x002C; sauf si on estime la balance b&eacute;n&eacute;fice-risque acceptable.<\/li>\n<li>L&rsquo;allaitement n&rsquo;est pas recommand&eacute;.<\/li>\n<\/ul>\n<p> <u>Pr&eacute;cautions particuli&egrave;res<\/u> <\/p>\n<ul>\n<li>Des r&eacute;actions s&eacute;v&egrave;res d&rsquo;hypersensibilit&eacute; (y compris anaphylaxie)&#x002C; ainsi que des infections graves avec d&eacute;c&egrave;s ont &eacute;t&eacute; d&eacute;crites.<\/li>\n<li>Comme pour les autres anticorps monoclonaux&#x002C; l&rsquo;administration de vaccins vivants doit &ecirc;tre &eacute;vit&eacute;e.<\/li>\n<li>Dans les &eacute;tudes&#x002C; des cancers sont apparus chez 1&#x002C;2% des patients sous anifrolumab contre 0&#x002C;6% des patients sous placebo.<span class='folia-referentie-note'>4<\/span><\/li>\n<\/ul><\/div>\n<p><strong>Posologie&nbsp;<\/strong>: une perfusion toutes les 4 semaines<\/p>\n<p><strong>Co&ucirc;t&nbsp;<\/strong>: 874 &euro; pour un flacon de 300mg&#x002C; non rembours&eacute; au 1<sup>er<\/sup> avril 2023<\/p>\n<p> &nbsp;<\/p>\n<h3><a data-type='molecule' id='ibu' name='ibu'><\/a>ibuprof&egrave;ne + parac&eacute;tamol IV (Combogesic&reg;<span class='mp-kidney-m'> <\/span>)<\/h3>\n<div class='summary'><b>L&rsquo;association d&rsquo;ibuprof&egrave;ne + parac&eacute;tamol<\/b> est commercialis&eacute;e sous forme de solution pour <b>perfusion intraveineuse<\/b> (<b>Combogesic&reg;<span class='mp-kidney-m'> <\/span>&#x002C;&nbsp;<\/b>un flacon de 100 ml contenant 1 gr de parac&eacute;tamol et 300 mg d&rsquo;ibuprof&egrave;ne&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=6510'>chapitre 8.2.4<\/a>&#x002C; usage hospitalier). Elle a pour indication le <b>traitement &agrave; court terme de la douleur mod&eacute;r&eacute;e aigu&euml;<\/b> quand la voie d&rsquo;administration intraveineuse est n&eacute;cessaire (synth&egrave;se du RCP).<br \/> Selon le RCP&#x002C; cette association n&rsquo;a &eacute;t&eacute; &eacute;valu&eacute;e qu&rsquo;en post-op&eacute;ratoire de cure d&rsquo;hallux valgus.<br \/> Bien que son indication soit large (douleur mod&eacute;r&eacute;e aigu&euml;)&#x002C; son <b>usage<\/b> est <b>&agrave; r&eacute;server &agrave; un usage hospitalier<\/b>. L&rsquo;association de deux compos&eacute;s <b>augmente le risque de toxicit&eacute;<\/b> et <b>diminue la flexibilit&eacute; posologique<\/b>.<br \/> Le profil d&rsquo;innocuit&eacute; est celui de l&rsquo;<a href='https:\/\/www.cbip.be\/fr\/chapters\/10?frag=6775'>ibuprof&egrave;ne<\/a> et du <a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=6429'>parac&eacute;tamol<\/a>.<span class='folia-referentie-note'>1<\/span><\/div>\n<p><b>Co&ucirc;t<\/b>&nbsp;:&nbsp;48&euro; pour 10 flacons&#x002C; non rembours&eacute; au 1<sup>er<\/sup> avril 2023.<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='peg' name='peg'><\/a>pegc&eacute;tacoplan (Aspaveli&reg;\u25bc<span class='ot'> <\/span>)<\/h3>\n<div class='summary'><b>Le pegc&eacute;tacoplan (Aspaveli&reg;<\/b>\u25bc<span class='ot'> <\/span><b>&#x002C;&nbsp;<\/b><a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8903932'>chapitre 12.3.2.6.6<\/a>&#x002C; m&eacute;dicament orphelin&#x002C; <b>perfusion sous-cutan&eacute;e<\/b>&#x002C; d&eacute;livrance hospitali&egrave;re) est un <b>immunomodulateur<\/b> qui bloque la prot&eacute;ine C3 du compl&eacute;ment. Il a pour indication le traitement de <b>l&rsquo;h&eacute;moglobinurie paroxystique nocturne<\/b> chez les adultes an&eacute;miques malgr&eacute; un traitement par inhibiteur de C5 pendant au moins 3 mois (synth&egrave;se du RCP).<br \/> Le pegc&eacute;tacoplan semble <b>plus efficace que l&rsquo;&eacute;culizumab<\/b> pour augmenter l&rsquo;h&eacute;moglobine et diminuer le besoin de transfusions chez des patients avec une an&eacute;mie persistante malgr&eacute; un traitement par &eacute;culizumab.<br \/> Il expose fr&eacute;quemment &agrave; un <b>risque d&rsquo;infection (y compris des infections s&eacute;v&egrave;res) et d&rsquo;h&eacute;molyse<\/b>. Puisque l&rsquo;auto-administration est possible&#x002C; les <b>patients doivent &ecirc;tre avertis de ces risques<\/b> et des <b>signes &eacute;vocateurs<\/b>.<span class='folia-referentie-note'>1&#x002C;2<\/span><br \/> Du mat&eacute;riel Risk Minimization Activities (<a href='https:\/\/basededonneesdesmedicaments.be\/medicament\/62bc20378ab5583c18867a11\/rma'>RMA<\/a> <span class='ot'> <\/span>) est &agrave; disposition des professionnels de la sant&eacute;.<\/div>\n<div class='detailed-content'><b>Innocuit&eacute;<\/b><br \/> <u>Contre-indications<\/u> <\/p>\n<ul>\n<li>Infection non gu&eacute;rie due &agrave;&#x002C; ou absence de vaccination &agrave; m&eacute;ningocoque&#x002C; pneumocoque ou <i>Haemophilus influenzae<\/i>.<\/li>\n<\/ul>\n<p> <u>Effets ind&eacute;sirables<\/u> <\/p>\n<ul>\n<li>Les plus fr&eacute;quents (&gt;10%)&nbsp;: infections des voies respiratoires sup&eacute;rieures&#x002C; infections urinaires&#x002C; h&eacute;molyse&#x002C; c&eacute;phal&eacute;es&#x002C; vertiges&#x002C; toux&#x002C; troubles gastro-intestinaux&#x002C; douleurs musculo-squelettiques&#x002C; fi&egrave;vre&#x002C; fatigue&#x002C; r&eacute;action au site d&rsquo;injection&#x002C; complication de la vaccination.<\/li>\n<\/ul>\n<p> <u>Grossesse et allaitement<\/u> <\/p>\n<ul>\n<li>Il est pr&eacute;f&eacute;rable d&rsquo;utiliser une contraception jusqu&rsquo;&agrave; 8 semaines apr&egrave;s l&rsquo;arr&ecirc;t du traitement.<\/li>\n<li>Par manque de donn&eacute;es&#x002C; l&rsquo;allaitement n&rsquo;est pas recommand&eacute; pendant la dur&eacute;e du traitement.<\/li>\n<\/ul>\n<p> <u>Pr&eacute;cautions particuli&egrave;res<\/u> <\/p>\n<ul>\n<li>Mesures &agrave; pr&eacute;voir\n<ul>\n<li>Vaccination contre le m&eacute;ningocoque&#x002C; pneumocoque et <i>Haemophilus influenzae<\/i> au moins 2 semaines avant le d&eacute;but du traitement.<\/li>\n<li>Surveillance des signes et sympt&ocirc;mes d&rsquo;h&eacute;molyse : fatigue&#x002C; h&eacute;moglobinurie&#x002C; douleurs abdominales&#x002C; dyspn&eacute;e&#x002C; thrombose&#x002C; dysphagie&#x002C; dysfonction &eacute;rectile&#x002C; mesure r&eacute;guli&egrave;re des LDH.<\/li>\n<\/ul>\n<\/li>\n<li>Avertir les patients des signes &eacute;vocateurs\n<ul>\n<li>D&rsquo;infection due &agrave; m&eacute;ningocoque&#x002C; pneumocoque ou <i>Haemophilus influenzae<\/i>.<\/li>\n<li>D&rsquo;une r&eacute;action &agrave; la perfusion (y compris l&rsquo;anaphylaxie).<span class='folia-referentie-note'>1<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/div>\n<p><strong>Posologie&nbsp;<\/strong>: une perfusion sous-cutan&eacute;e 2 fois par semaine.<\/p>\n<p> <strong>Co&ucirc;t&nbsp;<\/strong>: 3231&euro; pour une perfusion (25 848&euro; pour un mois de traitement)&#x002C; rembours&eacute; en a&nbsp;!.<\/p>\n<p> &nbsp;<\/p>\n<h2><a class='section' id='removed-molecules-small'><span class='removed-molecules-small'>&nbsp;<\/span><\/a>Arr&ecirc;ts de commercialisation<\/h2>\n<p>Cette rubrique concerne les arr&ecirc;ts d&eacute;finitifs de commercialisation. Les sp&eacute;cialit&eacute;s concern&eacute;es ne sont plus mentionn&eacute;es dans le R&eacute;pertoire.<br \/> La liste des m&eacute;dicaments indisponibles peut &ecirc;tre consult&eacute;e sur le <a href='https:\/\/www.pharmastatut.be\/'>site de l&rsquo;AFMPS-Pharmastatut<\/a><a>.<\/a><br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='ace' name='ace'><\/a>acide ac&eacute;tylsalicylique + caf&eacute;ine (Aspirine Cafeine&reg;)<\/h3>\n<p><b>L&rsquo;association d&rsquo;acide ac&eacute;tylsalicylique et de caf&eacute;ine<\/b> (Aspirine Cafeine&reg;) n&rsquo;est <b>plus commercialis&eacute;e<\/b>. Il existe encore des <a href='https:\/\/www.cbip.be\/fr\/chapters\/9?frag=19901'>sp&eacute;cialit&eacute;s associant ces deux compos&eacute;s au parac&eacute;tamol<\/a>. Un faible effet analg&eacute;sique additif est constat&eacute; en cas d&rsquo;ajout de caf&eacute;ine &agrave; un antidouleur&#x002C; mais uniquement pour des hauts dosages de caf&eacute;ine (&gt; 100 mg)&#x002C; ce qui n&rsquo;est pas le cas des associations commercialis&eacute;es. <b>L&rsquo;ajout de caf&eacute;ine<\/b> pourrait en outre favoriser un <b>usage abusif<\/b>. Pour la prise en charge de la <b>douleur<\/b>&#x002C; il faut en principe donner la <b>pr&eacute;f&eacute;rence <\/b>aux pr&eacute;parations contenant un <b>seul principe actif<\/b><a>.<\/a><br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='dis' name='dis'><\/a>disulfirame (Antabuse&reg;)<\/h3>\n<p>La sp&eacute;cialit&eacute; &agrave; base de <b>disulfirame<\/b> (<b>Antabuse&reg;<\/b>) n&rsquo;est <b>plus commercialis&eacute;e&nbsp;<\/b><font><b>en raison de la pr&eacute;sence&nbsp;d&#39;impuret&eacute;s&nbsp;<\/b>potentiellement canc&eacute;rog&egrave;nes en cas d&#39;usage prolong&eacute; (N-nitrosodi&eacute;thylamine&nbsp;:&nbsp;<\/font><font>NDEA<\/font><font>)<\/font><font>.<\/font><font>&nbsp;Pour plus d&#39;informations sur les nitrosamines&#x002C; voir &quot;<a href='https:\/\/https:\/\/www.ema.europa.eu\/en\/human-regulatory\/post-authorisation\/referral-procedures\/nitrosamine-impurities'>Nitrosamines Impurities sur le site de l&#39;EMA<\/a>&quot;<\/font>. Elle &eacute;tait utilis&eacute;e comme th&eacute;rapie dissuasive dans la pris en charge du <a href='https:\/\/www.cbip.be\/fr\/chapters\/11?frag=8375'>sevrage &eacute;thylique<\/a>. Le disulfirame n&rsquo;&eacute;tait pas un premier choix&#x002C; mais sa <b>disparition peut poser probl&egrave;me<\/b> chez certains patients qui l&rsquo;utilisaient. Il n&rsquo;existe <b>pas d&rsquo;alternative<\/b> avec un mode d&rsquo;action similaire.&nbsp;<\/p>\n<h3><a data-type='molecule' id='ery' name='ery'><\/a>&eacute;rythromycine + benzoyle peroxyde &agrave; usage cutan&eacute; (Benzadermine&reg;)<\/h3>\n<p>L&rsquo;association &agrave; base <b>d&rsquo;&eacute;rythromycine et de benzoyle peroxyde &agrave; usage cutan&eacute;<\/b> (Benzadermine&reg;) n&rsquo;est <b>plus commercialis&eacute;e<\/b>. Dans la <a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=14415'><b>prise en charge de l&rsquo;acn&eacute;<\/b><\/a>&#x002C; le <b>premier choix<\/b> selon la <a href='https:\/\/www.cbip.be\/fr\/chapters\/12?frag=8000630'>BAPCOC<\/a> est la <b>clindamycine 1%<\/b>. L&rsquo;&eacute;rythromycine 2% en magistrale est une alternative. Les associations exposent &agrave; plus de risque d&rsquo;effets ind&eacute;sirables et les possibilit&eacute;s d&rsquo;adaptation posologiques&nbsp;sont plus limit&eacute;es.<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='fro' name='fro'><\/a>frovatriptan (Migard&reg;)<\/h3>\n<p>La sp&eacute;cialit&eacute; &agrave; base de frovatriptan (Migard&reg;) n&rsquo;est plus commercialis&eacute;e. L&rsquo;autre sp&eacute;cialit&eacute; &agrave; base de frovatriptan (Frovatex&reg;) est en interruption de commercialisation jusque fin d&eacute;cembre 2023. Il n&rsquo;y a de fait <b>plus de frovatriptan sur le march&eacute; pour l&rsquo;instant<\/b>. D&rsquo;autres <a href='https:\/\/www.cbip.be\/fr\/chapters\/11?frag=9167'>triptans<\/a> sont disponibles pour la <a href='https:\/\/www.cbip.be\/fr\/chapters\/11?frag=9159'>prise en charge des crises migraineuses<\/a>.<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='sel' name='sel'><\/a>sulfure de s&eacute;l&eacute;nium (Selsun&reg;)<\/h3>\n<p>Le <b>sulfure de s&eacute;l&eacute;nium sous forme de shampoing<\/b> (Selsun&reg;) n&rsquo;est <b>plus commercialis&eacute;<\/b>. Pour le <a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=14050'>traitement de mycoses<\/a> telles que la <b>s&eacute;borrh&eacute;e du cuir chevelu<\/b> ou le <b>pityriasis versicolor<\/b>&#x002C; le <a href='https:\/\/www.cbip.be\/fr\/chapters\/16?frag=14076'><b>k&eacute;toconazole sous forme de shampoing<\/b><\/a> est une <b>alternative<\/b>.<\/p>\n<p> &nbsp;<\/p>\n<h2><a class='section' id='removed-molecules-small'><span class='removed-molecules-small'>&nbsp;<\/span><\/a>Interruptions de commercialisation (indisponibilit&eacute;s de longue dur&eacute;e)<\/h2>\n<p>Cette rubrique concerne les interruptions de commercialisation (ou indisponibilit&eacute;s de longue dur&eacute;e)&nbsp;d&rsquo;une dur&eacute;e pr&eacute;vue de plus d&rsquo;un an. Ces interruptions sont signal&eacute;es par ce sigle dans le r&eacute;pertoire: <span class='temp-end-commercialization'> <\/span><br \/> Les indisponibilit&eacute;s temporaires (dur&eacute;e pr&eacute;vue de moins d&rsquo;un an) ne sont pas reprises ici&#x002C; elles sont signal&eacute;es dans le r&eacute;pertoire par ce sigle: <span class='supply-problem'><\/span><br \/> La liste des m&eacute;dicaments indisponibles peut &ecirc;tre consult&eacute;e sur le <a href='https:\/\/www.pharmastatut.be\/'>site de l&rsquo;AFMPS-Pharmastatut<\/a>.<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='naf' name='naf'><\/a>naftazone (Mediaven&reg;)<\/h3>\n<p>La naftozone est en interruption de commercialisation jusqu&rsquo;en septembre 2023 en raison de probl&egrave;mes de production prolong&eacute;s. Certains <a href='https:\/\/www.cbip.be\/fr\/chapters\/2?frag=1487'>veinotropes<\/a> sont disponibles. Ils pourraient soulager temporairement la g&ecirc;ne et diminuer l&rsquo;&oelig;d&egrave;me&#x002C; mais leur efficacit&eacute; sur l&rsquo;&eacute;volution de l&rsquo;insuffisance veineuse n&rsquo;est pas d&eacute;montr&eacute;e. Les mesures non-m&eacute;dicamenteuses sont &agrave; conseiller au patient&nbsp;: bas de contention&#x002C; activit&eacute; physique&#x002C; et &eacute;viter la station debout prolong&eacute;e<a>.<\/a><br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='som' name='som'><\/a>somatostatine (Somatostatine-Belpharma&reg; et Somatostatine-Eumedica&reg;)<\/h3>\n<p>La <a href='https:\/\/www.cbip.be\/fr\/chapters\/6?frag=5108'>somatostatine<\/a> est en interruption de commercialisation jusque fin septembre 2023 en raison de probl&egrave;mes de production prolong&eacute;s. Elle est utilis&eacute;e pour le traitement de certaines fistules digestives&#x002C; l&rsquo;hypers&eacute;cr&eacute;tion li&eacute;e &agrave; des tumeurs endocrines digestives&#x002C; et les h&eacute;morragies par rupture de varices oesophagiennes.&nbsp;<br \/> &nbsp;<\/p>\n<h3><a data-type='molecule' id='uro' name='uro'><\/a>urokinase (Actosolv&reg;)<\/h3>\n<p>L&rsquo;urokinase est en interruption de commercialisation jusque fin novembre 2023. D&rsquo;autres <a href='https:\/\/www.cbip.be\/fr\/chapters\/3?frag=2204'>thrombolytiques<\/a> sont disponibles mais de fa&ccedil;on limit&eacute;e pour le traitement des embolies pulmonaires et thromboses art&eacute;rielles ou veineuses.<\/p>\n<p> &nbsp;<\/p>\n<h2>Sources<\/h2>\n<p>En plus des sources g&eacute;n&eacute;rales consult&eacute;es syst&eacute;matiquement par le CBIP (British Medical Journal&#x002C; New England Journal of Medicine&#x002C; Annals of Internal Medicine&#x002C; The Lancet&#x002C; JAMA&#x002C; Drug &amp; Therapeutic Bulletin&#x002C; GeBu&#x002C; La Revue Prescrire&#x002C; Australian Prescriber)&#x002C; pour &eacute;crire les articles &laquo;&nbsp;nouveaut&eacute;s m&eacute;dicamenteuses&nbsp;&raquo;&#x002C; les sources suivantes sont consult&eacute;es : RCP et dossier d&rsquo;&eacute;valuation &agrave; l&rsquo;EMA (EPAR) du produit&#x002C; The Medical Letter&#x002C; NEJM Journal Watch.<br \/> &nbsp;<\/p>\n<h2>Sources g&eacute;n&eacute;rales<\/h2>\n<p><span class='folia-referentie-tekst'>&#8211;&nbsp;Farmacotherapeutisch Kompas&#x002C; <a href='https:\/\/www.farmacotherapeutischkompas.nl\/'>https:\/\/www.farmacotherapeutischkompas.nl\/<\/a>&#x002C; consult&eacute; la derni&egrave;re fois le 5 avril 2023.<\/span><br \/> &nbsp;<\/p>\n<h2>Sources sp&eacute;cifiques<\/h2>\n<h3>anifrolumab<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Rev Prescrire 2023 ; 43 (472) : 91-94<br \/> <span class='folia-referentie-nummer'>2<\/span> Anifrolumab for systemic lupus erythematosus. Aust Prescr 2022;45:177-8. First published 1 September 2022. <a href='https:\/\/doi.org\/10.18773\/austprescr.2022.059'>https:\/\/doi.org\/10.18773\/austprescr.2022.059<\/a><br \/> <span class='folia-referentie-nummer'>3<\/span> Med Lett Drugs Ther. 2021 Sep 20;63(1633):146-7<br \/> <span class='folia-referentie-nummer'>4<\/span> <a href='https:\/\/www.ema.europa.eu\/en\/documents\/assessment-report\/klisyri-epar-assessment-report_en.pdf'>Saphnelo&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit (mars 2023)<\/a><br \/> <span class='folia-referentie-nummer'>5<\/span> Saphnelo-Avis de la Haute Autorit&eacute; de Sant&eacute; du 7 d&eacute;cembre 2022. <a href='https:\/\/www.has-sante.fr\/jcms\/p_3395767\/fr\/saphnelo-anifrolumab-lupus-erythemateux-systemique'>https:\/\/www.has-sante.fr\/jcms\/p_3395767\/fr\/saphnelo-anifrolumab-lupus-erythemateux-systemique<\/a><br \/> <span class='folia-referentie-nummer'>6<\/span> R Furie et al. Arthritis Rheumatol 2017; 69:376.<br \/> <span class='folia-referentie-nummer'>7<\/span> R Furie et al. Lancet Rheumatol 2019; 1:e208.&nbsp;<a href='https:\/\/www.thelancet.com\/journals\/lanrhe\/article\/PIIS2665-9913(19)30076-1\/fulltext'>https:\/\/www.thelancet.com\/journals\/lanrhe\/article\/PIIS2665-9913(19)30076-1\/fulltext<\/a><br \/> <span class='folia-referentie-nummer'>8<\/span> N Engl J Med 2020; 382:211-221. <a href='https:\/\/www.nejm.org\/doi\/10.1056\/NEJMoa1912196'>DOI: 10.1056\/NEJMoa1912196<\/a><br \/> &nbsp;<\/span><\/p>\n<h3>ibuprof&egrave;ne + parac&eacute;tamol IV<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Combogesic&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit (mars 2023)<\/span><br \/> &nbsp;<\/p>\n<h3>pegc&eacute;tacoplan<\/h3>\n<p class='reference'><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span> Rev Prescrire 2022 ; 42 (469) : 814-815<br \/> <span class='folia-referentie-nummer'>2<\/span> <a href='https:\/\/pubmed.ncbi.nlm.nih.gov\/32197106\/'>Aspaveli&reg;-R&eacute;sum&eacute; des Caract&eacute;ristiques du Produit&nbsp; (mars 2023)<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Nouveaut&eacute;s en m&eacute;decine sp&eacute;cialis&eacute;e &nbsp; &nbsp; &bull; anifrolumab (Saphnelo&reg;\u25bc):&nbsp;lupus &eacute;ryth&eacute;mateux  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-186592","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186592"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186592\/revisions"}],"predecessor-version":[{"id":189149,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186592\/revisions\/189149"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}