{"id":186548,"date":"2023-07-06T00:00:00","date_gmt":"2023-07-05T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/le-point-sur-lelbasvir-grazoprevir-zepatier-le-sofosbuvir-velpatasvir-epclusa-5-ans-apres-leur-commercialisation\/"},"modified":"2026-08-27T15:10:26","modified_gmt":"2026-08-27T13:10:26","slug":"le-point-sur-lelbasvir-grazoprevir-zepatier-le-sofosbuvir-velpatasvir-epclusa-5-ans-apres-leur-commercialisation","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/le-point-sur-lelbasvir-grazoprevir-zepatier-le-sofosbuvir-velpatasvir-epclusa-5-ans-apres-leur-commercialisation\/","title":{"rendered":"Le point sur l\u2019elbasvir + grazopr\u00e9vir (Zepatier\u00ae) &#038; le sofosbuvir + velpatasvir (Epclusa\u00ae), 5 ans apr\u00e8s leur commercialisation"},"content":{"rendered":"<div class='summary'>Des &eacute;tudes cliniques randomis&eacute;es &agrave; court terme ont montr&eacute; que les associations d&#39;antiviraux &agrave; action directe (AAD)&#x002C; telles que<b> <\/b>&rsquo;<b>elbasvir + grazopr&eacute;vir <\/b>(Zepatier&reg;&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/12?frag=25130'>chapitre 11.4.5.<\/a>)<b> <\/b>et<b> <\/b>le<b> sofosbuvir + velpatasvir <\/b>(Epclusa&reg;&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/12?frag=25130'>chapitre 11.4.5.<\/a>)&#x002C; ont une tr&egrave;s grande efficacit&eacute; (jusqu&#39;&agrave; &gt;90 %) sur la &laquo;&nbsp;r&eacute;ponse virologique soutenue&nbsp;&raquo; (RVS&#x002C; d&eacute;finie comme une charge virale ind&eacute;tectable &agrave; 12 ou 24 semaines)&nbsp;en cas d&rsquo;h&eacute;patite C chronique (<a href='https:\/\/www.cbip.be\/fr\/articles\/4073?folia=4050'>voir Folia d&rsquo;avril 2023<\/a>). Des &eacute;tudes observationnelles sugg&egrave;rent que le traitement par associations d&rsquo;AAD pourrait &ecirc;tre associ&eacute; &agrave; une r&eacute;duction significative de la mortalit&eacute; globale&#x002C; du cancer du foie et d&#39;autres complications h&eacute;patiques&#x002C; mais les effets &agrave; long terme et le profil de s&eacute;curit&eacute; doivent &ecirc;tre davantage document&eacute;s dans des &eacute;tudes observationnelles &agrave; grande &eacute;chelle. En raison des donn&eacute;es limit&eacute;es&#x002C; la question sur la s&eacute;curit&eacute; d&rsquo;emploi des AAD pendant la grossesse et l&#39;allaitement reste sans r&eacute;ponse.<br \/> Pour des informations plus compl&egrave;tes&#x002C; voir notre article <a href='https:\/\/www.cbip.be\/fr\/articles\/4073?folia=4050'>Dix ans plus tard&#x002C; le point sur les antiviraux &agrave; action directe dans l&rsquo;h&eacute;patite C<\/a> dans les Folia d&rsquo;avril 2023.<br \/> <b>Conclusion du CBIP&#x002C; 5 ans apr&egrave;s leur commercialisation<\/b>:<b> <\/b>Les associations d&#39;AAD&#x002C; telles <b>que l&rsquo;elbasvir + grazopr&eacute;vir et le sofosbuvir + velpatasvir<\/b>&#x002C; ont un r&ocirc;le important dans le traitement de l&#39;h&eacute;patite C chronique&#x002C; avec un taux d&rsquo;&eacute;radication virale tr&egrave;s &eacute;lev&eacute;&#x002C; mais que des &eacute;tudes observationnelles compl&eacute;mentaires sont n&eacute;cessaires pour confirmer leur impact sur la morbidit&eacute; et leur s&eacute;curit&eacute; &agrave; long terme.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des &eacute;tudes cliniques randomis&eacute;es &agrave; court terme ont montr&eacute; que  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20224,20213],"class_list":["post-186548","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags-nl","tag-import_tags"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186548"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186548\/revisions"}],"predecessor-version":[{"id":189105,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186548\/revisions\/189105"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}