{"id":186540,"date":"2023-08-24T00:00:00","date_gmt":"2023-08-23T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/le-point-sur-lixekizumab-taltz-5-ans-apres-sa-commercialisation\/"},"modified":"2026-07-09T15:11:56","modified_gmt":"2026-07-09T13:11:56","slug":"le-point-sur-lixekizumab-taltz-5-ans-apres-sa-commercialisation","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/le-point-sur-lixekizumab-taltz-5-ans-apres-sa-commercialisation\/","title":{"rendered":"Le point sur l\u2019ix\u00e9kizumab (Taltz\u00ae), 5 ans apr\u00e8s sa commercialisation"},"content":{"rendered":"<div class='summary'><a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=26294'>L&#39;ix&eacute;kizumab<\/a> (Taltz&reg;&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/13?frag=8902694'>chapitre 13.3.2.2.7.<\/a>)&#x002C; un inhibiteur de l&#39;IL-17&#x002C; a &eacute;t&eacute; commercialis&eacute; il y a 5 ans pour le traitement du psoriasis mod&eacute;r&eacute; &agrave; s&eacute;v&egrave;re chez l&#39;adulte. Voir l&rsquo;article dans les <a href='https:\/\/www.cbip.be\/fr\/articles\/2850?folia=2845'>Folia de mars 2018 (mise &agrave; jour 22\/10\/2019)<\/a> qui fait le point sur de la prise en charge du psoriasis en plaques. L&#39;indication a depuis &eacute;t&eacute; &eacute;tendue au <b>psoriasis chez l&#39;enfant&#x002C; au rhumatisme psoriasique et &agrave; la spondyloarthrite axiale<\/b>. Le s&eacute;cukinumab (Cosentyx&reg;)&#x002C; un autre inhibiteur de l&#39;IL-17&#x002C; est autoris&eacute; dans les m&ecirc;mes indications. Nous renvoyons au <a href='https:\/\/www.cbip.be\/fr\/articles\/3660?folia=3658&amp;matches=secukinumab'>Folia d&rsquo;ao&ucirc;t 2021<\/a> pour une discussion d&eacute;taill&eacute;e du s&eacute;cukinumab&#x002C; qui s&rsquo;applique aussi &agrave; l&#39;ix&eacute;kizumab. Les inhibiteurs d&rsquo;IL sont utilis&eacute;s apr&egrave;s &eacute;chec des traitements conventionnels. Il n&#39;y a pas de pr&eacute;f&eacute;rence entre les diff&eacute;rents inhibiteurs de l&#39;IL-17.<\/p>\n<p> On sait que les inhibiteurs d&#39;IL sont associ&eacute;s &agrave; un risque accru d&#39;infections et pourraient &ecirc;tre associ&eacute;s &agrave; un risque accru de tumeurs malignes. Nous avons fait le point sur le risque de cancer dans le <a href='https:\/\/www.cbip.be\/fr\/articles\/3677?folia=3674'>Folia de septembre 2021<\/a>. Dans le cadre des maladies rhumatismales&#x002C; le nombre n&eacute;cessaire pour nuire (NNN) pour observer un cas suppl&eacute;mentaire de tumeur maligne est de 250&#x002C; par rapport au placebo. Les donn&eacute;es sont insuffisantes pour se prononcer sur le risque de tumeurs malignes dans le cadre du psoriasis.<\/p>\n<p> <strong>Conclusion du CBIP&#x002C; 5&nbsp;ans apr&egrave;s commercialisation&nbsp;<\/strong>: L&#39;indication de l&#39;ix&eacute;kizumab (psoriasis) a &eacute;t&eacute; &eacute;tendue au psoriasis chez l&#39;enfant et &agrave; certaines formes d&#39;arthropathie. Le risque d&#39;infections et de tumeurs malignes li&eacute; aux inhibiteurs d&rsquo;IL n&eacute;cessite la vigilance.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#39;ix&eacute;kizumab (Taltz&reg;&#x002C; chapitre 13.3.2.2.7.)&#x002C; un inhibiteur de l&#39;IL-17&#x002C; a &eacute;t&eacute;  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-186540","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186540"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186540\/revisions"}],"predecessor-version":[{"id":189097,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186540\/revisions\/189097"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}