{"id":186520,"date":"2023-10-19T00:00:00","date_gmt":"2023-10-18T22:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/lacide-hyaluronique-dans-larthrose-de-genou\/"},"modified":"2026-07-09T15:11:56","modified_gmt":"2026-07-09T13:11:56","slug":"lacide-hyaluronique-dans-larthrose-de-genou","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/lacide-hyaluronique-dans-larthrose-de-genou\/","title":{"rendered":"L\u2019acide hyaluronique dans l\u2019arthrose de genou ?"},"content":{"rendered":"<h2>Message cl&eacute;<\/h2>\n<p>Chez les patients souffrant d&#39;arthrose du genou&#x002C; une synth&egrave;se m&eacute;thodique r&eacute;cente avec m&eacute;ta-analyse confirme que l&rsquo;injection intra-articulaire d&rsquo;acide hyaluronique n&rsquo;apporte pas de b&eacute;n&eacute;fice cliniquement pertinent<span class='folia-referentie-nummer'><sup>1<\/sup><\/span>.<\/p>\n<h2>Qu&rsquo;entend-t-on par viscosuppl&eacute;mentation&nbsp;?<\/h2>\n<p>La viscosuppl&eacute;mentation (VS) se fait par injection intra-articulaire d&rsquo;acide hyaluronique&#x002C; une substance naturellement pr&eacute;sente dans divers types de tissus conjonctifs tels que la peau&#x002C; l&rsquo;humeur vitr&eacute;e&#x002C; le cartilage du nez et la synovie. En cas d&rsquo;arthrose&#x002C; la concentration en acide hyaluronique dans le liquide synovial diminue<span class='folia-referentie-nummer'><sup>2&#x002C;3<\/sup><\/span>.<br \/> L&rsquo;arthrose du genou (syn. gonarthrose) est une maladie chronique d&eacute;g&eacute;n&eacute;rative pouvant entrainer des douleurs aux genoux et une limitation fonctionnelle. Avec ses propri&eacute;t&eacute;s de chondro-protection&#x002C; l&rsquo;acide hyaluronique inject&eacute; soulagerait &agrave; la fois la douleur et faciliterait la cicatrisation des fissures cartilagineuses<span class='folia-referentie-nummer'><sup>1&#x002C;4<\/sup><\/span>.<br \/> Depuis plus de 50 ans&#x002C; la VS est utilis&eacute;e comme traitement symptomatique de l&rsquo;arthrose du genou. Pourtant&#x002C; son efficacit&eacute; et sa s&eacute;curit&eacute; font l&#39;objet de nombreux d&eacute;bats depuis la publication d&rsquo;une premi&egrave;re &eacute;tude clinique au d&eacute;but des ann&eacute;es 70<span class='folia-referentie-nummer'><sup>1&#x002C;2<\/sup><\/span>.<br \/> Les premiers produits &agrave; base d&rsquo;acide hyaluronique &eacute;taient d&rsquo;origine aviaire (extrait de cr&ecirc;tes de coq). Cette source d&rsquo;extraction &eacute;tant potentiellement allerg&egrave;ne&#x002C; un proc&eacute;d&eacute; de fabrication synth&eacute;tique (par fermentation bact&eacute;rienne) est aussi utilis&eacute;<span class='folia-referentie-nummer'><sup>3<\/sup><\/span>.<br \/> Sur le plan chimique&#x002C; l&rsquo;acide hyaluronique est un glycosaminoglycane caract&eacute;ris&eacute; par la r&eacute;p&eacute;tition de deux unit&eacute;s de base (l&#39;acide D-glucuronique et la N-ac&eacute;tylglucosamine)&#x002C; ce qui&nbsp; conf&egrave;re au liquide synovial des propri&eacute;t&eacute;s visqueuses et &eacute;lastiques. D&rsquo;une marque &agrave; l&rsquo;autre&#x002C; les poids mol&eacute;culaires de ces produits ainsi que leur viscosit&eacute; sont tr&egrave;s variables&#x002C; ce qui influence leur fr&eacute;quence d&rsquo;injection<span class='folia-referentie-nummer'><sup>5<\/sup><\/span>.<\/p>\n<h2>Protocole de l&rsquo;&eacute;tude<\/h2>\n<ul>\n<li>\n<p>Cette synth&egrave;se m&eacute;thodique avec m&eacute;ta-analyse identifie 169 &eacute;tudes randomis&eacute;es&#x002C; ou quasi-randomis&eacute;es&#x002C; publi&eacute;es ou non&#x002C; dont au moins 75% des participants ont une gonarthrose clinique ou radiologique (voir &laquo;&nbsp;plus d&rsquo;infos&nbsp;&raquo;). Les &eacute;tudes comparent un d&eacute;riv&eacute; ou une pr&eacute;paration d&rsquo;acide hyaluronique par injection intra-articulaire versus un placebo (solution saline ou une pr&eacute;paration avec des concentrations n&eacute;gligeables d&rsquo;acide hyaluronique) ou aucune intervention. Ces &eacute;tudes comportent au moins un des trois crit&egrave;res d&rsquo;&eacute;valuation recherch&eacute;s (douleur&#x002C; capacit&eacute; fonctionnelle&#x002C; ou &eacute;v&egrave;nements ind&eacute;sirables graves). Seules les &eacute;tudes avec un nombre important de patients (&ge; 100 par groupe)&#x002C; randomis&eacute;es et avec groupe t&eacute;moin recevant un placebo&#x002C; ont &eacute;t&eacute; incluses dans la m&eacute;ta-analyse (voir &laquo;&nbsp;plus d&rsquo;infos&nbsp;&raquo;).<\/p>\n<\/li>\n<li>\n<p>Le crit&egrave;re d&rsquo;&eacute;valuation primaire est l&rsquo;intensit&eacute; de la douleur. Les crit&egrave;res d&rsquo;&eacute;valuation secondaires sont la capacit&eacute; fonctionnelle et les &eacute;v&egrave;nements ind&eacute;sirables graves. La douleur globale ou la douleur &agrave; la marche est not&eacute;e par le patient sur une &eacute;chelle visuelle analogique (EVA) ou mesur&eacute;e au moyen des &eacute;chelles standardis&eacute;es que sont le &laquo;&nbsp;WOMAC pain&nbsp;&raquo; ou le &laquo;&nbsp;Lequesne Index&nbsp;&raquo;. La capacit&eacute; fonctionnelle est mesur&eacute;e via les scores &laquo;&nbsp;WOMAC function&nbsp;&raquo; ou &laquo;&nbsp;Lequesne Index&nbsp;&raquo;. La diff&eacute;rence de douleur et de capacit&eacute; fonctionnelle entre les groupes placebo et interventionnel est exprim&eacute;e par une diff&eacute;rence moyenne standardis&eacute;e (DMS). La DMS devait &ecirc;tre d&rsquo;au moins -0&#x002C;37 pour &ecirc;tre jug&eacute;e cliniquement pertinente par les auteurs. Les &eacute;v&egrave;nements ind&eacute;sirables graves sont exprim&eacute;s en risque relatif.<\/p>\n<\/li>\n<li>\n<p>Sont notamment consid&eacute;r&eacute;s comme &eacute;v&egrave;nements ind&eacute;sirables graves&nbsp;: tout &eacute;v&egrave;nement n&eacute;cessitant une hospitalisation ou une prolongation d&rsquo;hospitalisation&#x002C; tout &eacute;v&egrave;nement entra&icirc;nant une incapacit&eacute; majeure ou durable&#x002C; et tout &eacute;v&egrave;nement fatal ou potentiellement fatal.<br \/> <!--[if supportFields]><span style=\u2019font-size:12.0pt;line-height:150%;font-family:'Calibri'&#x002C;sans-serif; mso-ascii-theme-font:minor-latin;mso-fareast-font-family:Calibri;mso-hansi-theme-font: minor-latin;mso-bidi-theme-font:minor-latin;mso-ansi-language:NL-BE;mso-fareast-language: NL-BE;mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/p>\n<div class='detailed-content'>\n<ul>\n<li>Quelques chiffres sur les 169 &eacute;tudes (21 163 participants) identifi&eacute;es : la m&eacute;diane de la taille des &eacute;chantillons est de 92 participants (<a href='https:\/\/www.minerva-ebp.be\/Home\/Glossary?alpha=i#glossaryId34'>&eacute;cart interquartile<\/a> 50 &#8211; 165). Le follow-up m&eacute;dian des &eacute;tudes est de 24 semaines (8&#x002C;6 &#8211; 27). L&rsquo;&acirc;ge m&eacute;dian des participants masculins est de 61 ans (58 &#8211; 64)&#x002C; et des participantes f&eacute;minines de 62 ans (54 &#8211; 71). Le b&eacute;n&eacute;fice clinique de la VS est le plus souvent constat&eacute; dans des &eacute;tudes ouvertes (93 &eacute;tudes comme compl&eacute;ment d&rsquo;un traitement standard compar&eacute; &agrave; un traitement standard seul)&#x002C; suivi par des &eacute;tudes contr&ocirc;l&eacute;es par placebo (76 &eacute;tudes).<!--[if gte mso 9]><xml> <\/xml><![endif]--><!--[if supportFields]><span style=\u2019font-size:12.0pt; line-height:150%;font-family:'Calibri'&#x002C;sans-serif;mso-ascii-theme-font:minor-latin; mso-fareast-font-family:Calibri;mso-hansi-theme-font:minor-latin;mso-bidi-font-family: 'Times New Roman';mso-ansi-language:NL-BE;mso-fareast-language:NL-BE; mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/li>\n<li>Les &eacute;tudes incluses dans la m&eacute;ta-analyse sont au nombre de 25 avec uniquement des RCT de plus de 100 participants. Les 9 423 participants ont un &acirc;ge moyen de 62 ans. La dur&eacute;e m&eacute;diane du suivi apr&egrave;s la derni&egrave;re injection est de 13 semaines pour la douleur et de 12 semaines pour la capacit&eacute; fonctionnelle. Le nombre m&eacute;dian d&#39;injections par cycle &eacute;tait de 3&#x002C; tant pour le crit&egrave;re de l&#39;intensit&eacute; de la douleur que pour celui de la capacit&eacute; fonctionnelle. La plupart des &eacute;tudes comporte un cycle.<!--[if gte mso 9]><xml> <\/xml><![endif]--><!--[if supportFields]><span style=\u2019font-size:12.0pt; line-height:150%;font-family:'Calibri'&#x002C;sans-serif;mso-ascii-theme-font:minor-latin; mso-fareast-font-family:Calibri;mso-hansi-theme-font:minor-latin;mso-bidi-font-family: 'Times New Roman';mso-ansi-language:NL-BE;mso-fareast-language:NL-BE; mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><!--[if supportFields]><span style=\u2019font-size:12.0pt; line-height:150%;font-family:'Calibri'&#x002C;sans-serif;mso-ascii-theme-font:minor-latin; mso-fareast-font-family:Calibri;mso-hansi-theme-font:minor-latin;mso-bidi-font-family: 'Times New Roman';mso-ansi-language:NL-BE;mso-fareast-language:NL-BE; mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/li>\n<\/ul><\/div>\n<\/li>\n<\/ul>\n<h2>R&eacute;sultats en bref<\/h2>\n<ul>\n<li>\n<p>La VS entraine :<\/p>\n<ul>\n<li>\n<p>une r&eacute;duction cliniquement non pertinente de la <b>douleur<\/b> li&eacute;e &agrave; l&rsquo;arthrose du genou&#x002C; par rapport au placebo (voir &laquo;&nbsp;plus d&rsquo;infos&nbsp;&raquo;)&#x002C;<\/p>\n<\/li>\n<li>\n<p>une am&eacute;lioration cliniquement non pertinente de la <b>capacit&eacute; fonctionnelle<\/b> du genou&#x002C; par rapport au placebo (voir &laquo;&nbsp;plus d&rsquo;infos&nbsp;&raquo;)&#x002C;<\/p>\n<\/li>\n<li>\n<p>un risque statistiquement significatif plus &eacute;lev&eacute; d&rsquo;<b>&eacute;v&egrave;nements<\/b> <b>ind&eacute;sirables<\/b>&#x002C; par rapport au placebo (voir &laquo;&nbsp;plus d&rsquo;infos&nbsp;&raquo;). La plupart des publications ne mentionnent pas de d&eacute;tails et les auteurs se contentent d&rsquo;indiquer qu&rsquo;il n&rsquo;y a pas d&rsquo;association avec l&rsquo;intervention.<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p>Selon les auteurs de la synth&egrave;se&#x002C; le risque de biais &eacute;tait faible dans la plupart des RCT.<br \/> <!--[if supportFields]><span style=\u2019font-size:12.0pt;line-height:150%;font-family:'Calibri'&#x002C;sans-serif; mso-ascii-theme-font:minor-latin;mso-fareast-font-family:Calibri;mso-hansi-theme-font: minor-latin;mso-bidi-theme-font:minor-latin;mso-ansi-language:NL-BE;mso-fareast-language: NL-BE;mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/p>\n<div class='detailed-content'>\n<ul>\n<li>Le crit&egrave;re de la <i>douleur<\/i> est analys&eacute; dans 24 &eacute;tudes contr&ocirc;l&eacute;es par placebo (8&nbsp;997 participants randomis&eacute;s). Elles indiquent que la VS entra&icirc;ne une l&eacute;g&egrave;re r&eacute;duction de la douleur li&eacute;e &agrave; l&#39;arthrose du genou par rapport au placebo&#x002C; cliniquement non pertinente (DMS -0&#x002C;08&#x002C; 95% IC -0&#x002C;15 &agrave; -0&#x002C;02)&#x002C; la diff&eacute;rence &eacute;tant nettement inf&eacute;rieure au seuil de pertinence clinique. Cette diminution de douleur correspond &agrave; une r&eacute;duction de -2&#x002C;0 mm (95% IC -3&#x002C;8 &agrave; -0&#x002C;5 mm) sur une &eacute;chelle visuelle analogique de 100 mm&#x002C; compar&eacute; au placebo.<!--[if gte mso 9]><xml> <\/xml><![endif]--><!--[if supportFields]><span style=\u2019font-size:12.0pt; line-height:150%;font-family:'Calibri'&#x002C;sans-serif;mso-ascii-theme-font:minor-latin; mso-fareast-font-family:Calibri;mso-hansi-theme-font:minor-latin;mso-bidi-font-family: 'Times New Roman';mso-ansi-language:NL-BE;mso-fareast-language:NL-BE; mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/li>\n<li>Le crit&egrave;re de la <i>capacit&eacute; fonctionnelle<\/i> est analys&eacute; dans 19 &eacute;tudes contr&ocirc;l&eacute;es par placebo (6&nbsp;307 participants randomis&eacute;s). D&rsquo;apr&egrave;s ces &eacute;tudes&#x002C; la VS est associ&eacute;e &agrave; une l&eacute;g&egrave;re am&eacute;lioration du niveau fonctionnel du genou&#x002C; mais cliniquement non pertinente (DMS -0&#x002C;11&#x002C; IC &agrave; 95% de -0&#x002C;18 &agrave; -0&#x002C;05).<!--[if gte mso 9]><xml> <\/xml><![endif]--><!--[if supportFields]><span style=\u2019font-size:12.0pt; line-height:150%;font-family:'Calibri'&#x002C;sans-serif;mso-ascii-theme-font:minor-latin; mso-fareast-font-family:Calibri;mso-hansi-theme-font:minor-latin;mso-bidi-font-family: 'Times New Roman';mso-ansi-language:NL-BE;mso-fareast-language:NL-BE; mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/li>\n<li>Les &eacute;v&egrave;nements <i>ind&eacute;sirables graves<\/i> ont &eacute;t&eacute; analys&eacute;s sur base de 15 larges &eacute;tudes contr&ocirc;l&eacute;es par placebo (6 462 participants randomis&eacute;s). La VS est associ&eacute;e &agrave; un risque statistiquement significatif plus &eacute;lev&eacute; d&rsquo;&eacute;v&egrave;nements ind&eacute;sirables par rapport au placebo (risque relatif 1&#x002C;49&#x002C; IC &agrave; 95% de 1&#x002C;12 &agrave; 1&#x002C;98). Au total&#x002C; 3&#x002C;7% des patients recevant une VS et 2&#x002C;5% des patients recevant le placebo ont souffert d&rsquo;un &eacute;v&egrave;nement ind&eacute;sirable grave. La plupart des publications ne mentionnent pas de d&eacute;tails et les auteurs se contentent d&rsquo;indiquer qu&rsquo;il n&rsquo;y a pas d&rsquo;association avec l&rsquo;intervention.<!--[if supportFields]><span style=\u2019font-size:12.0pt; line-height:150%;font-family:'Calibri'&#x002C;sans-serif;mso-ascii-theme-font:minor-latin; mso-fareast-font-family:Calibri;mso-hansi-theme-font:minor-latin;mso-bidi-font-family: 'Times New Roman';mso-ansi-language:NL-BE;mso-fareast-language:NL-BE; mso-bidi-language:AR-SA\u2019><span style=\u2019mso-element:field-end\u2019><\/span><\/span><![endif]--><\/li>\n<\/ul><\/div>\n<\/li>\n<\/ul>\n<h2>Discussion<\/h2>\n<ul>\n<li>\n<p>Cette synth&egrave;se m&eacute;thodique apporte des preuves de haute qualit&eacute; sur l&rsquo;absence de b&eacute;n&eacute;fice cliniquement pertinent de la VS chez les patients souffrant d&rsquo;arthrose du genou&#x002C; et sur l&rsquo;association entre la VS et le risque d&rsquo;&eacute;v&egrave;nements ind&eacute;sirables graves&#x002C; par rapport au placebo. Cette &eacute;tude syst&eacute;matique contient 80 &eacute;tudes en plus (8 796 participants) qu&rsquo;une revue importante publi&eacute;e en 2012<span class='folia-referentie-nummer'><sup>6<\/sup><\/span>. Cette augmentation spectaculaire du nombre d&rsquo;&eacute;tudes&nbsp;soul&egrave;ve des questions d&rsquo;ordre &eacute;thique&#x002C; vu qu&#39;il existait d&eacute;j&agrave; suffisamment de preuves pour r&eacute;futer les avantages de la VS.<\/p>\n<\/li>\n<li>\n<p>Cette synth&egrave;se m&eacute;thodique inclue des &eacute;tudes publi&eacute;es et non publi&eacute;es. Une lacune des synth&egrave;ses pr&eacute;c&eacute;dentes &eacute;tait qu&rsquo;elles n&rsquo;incluaient pas les &eacute;tudes non publi&eacute;es. Ce biais de publication peut expliquer les r&eacute;sultats plus positifs de ces synth&egrave;ses.<span class='folia-referentie-nummer'><sup>6&#x002C;10<\/sup><\/span><\/p>\n<\/li>\n<li>\n<p>Une limite de cette synth&egrave;se m&eacute;thodique est que les crit&egrave;res d&rsquo;exclusion n&rsquo;apparaissent pas clairement dans la publication&#x002C; ni dans les annexes. L&rsquo;origine de l&rsquo;acide hyaluronique varie aussi d&rsquo;une &eacute;tude &agrave; l&rsquo;autre. Aucune information d&eacute;taill&eacute;e nous est donn&eacute;e au sujet des &eacute;v&egrave;nements ind&eacute;sirables. Il est plausible que le risque accru d&rsquo;&eacute;v&egrave;nements ind&eacute;sirables li&eacute;s &agrave; la VS soit plus marqu&eacute; en pratique courante&#x002C; car elle concerne des patients plus fragiles que dans les &eacute;tudes cliniques.<\/p>\n<\/li>\n<\/ul>\n<h2>Conclusion et ce que les recommandations disent<\/h2>\n<ul>\n<li>\n<p>Les r&eacute;sultats de cette publication ne soutiennent pas l&#39;utilisation de la VS pour soulager les sympt&ocirc;mes li&eacute;s &agrave; l&#39;arthrose du genou. Sur le plan international&#x002C; les &nbsp;guidelines les plus r&eacute;centes ne sont pas unanimes. Du c&ocirc;t&eacute; anglais (recommandations du NICE) et am&eacute;ricain (recommandations de l&rsquo;AAOS et de l&rsquo;ACR)&#x002C; les guidelines recommandent de ne pas pratiquer ce type d&rsquo;injection chez les patients souffrant d&rsquo;arthrose du genou. Par contre&#x002C; la soci&eacute;t&eacute; internationale OARSI le recommande<span class='folia-referentie-nummer'><sup>3&#x002C;8<\/sup><\/span>.<\/p>\n<\/li>\n<li>\n<p>En Belgique&#x002C; la plupart des d&eacute;riv&eacute;s de l&rsquo;acide hyaluronique sont en vente libre sous forme de dispositif m&eacute;dical. Ce statut ne requiert pas des proc&eacute;dures d&rsquo;enregistrement strictes&#x002C; rendant sa commercialisation plus rapide. Le seul d&eacute;riv&eacute; enregistr&eacute; comme m&eacute;dicament est le Hyalgan&reg;<br \/> (cf. <a href='https:\/\/www.cbip.be\/fr\/chapters\/10'>R&eacute;pertoire 9.4.2 Acide hyaluronique<\/a>). Le principe actif du Hyalgan&reg; est d&rsquo;origine aviaire et doit &ecirc;tre utilis&eacute; avec pr&eacute;caution chez les patients allergiques aux prot&eacute;ines aviaires&#x002C; aux plumes et aux produits &agrave; base d&rsquo;&oelig;ufs<span class='folia-referentie-nummer'><sup>10<\/sup><\/span>.<\/p>\n<\/li>\n<li>\n<p>L&#39;arthrose du genou &eacute;volue de mani&egrave;re fluctuante. Des pouss&eacute;es temporaires peuvent survenir r&eacute;guli&egrave;rement&#x002C; caract&eacute;ris&eacute;es par une augmentation des plaintes. La prise en charge de la douleur repose d&rsquo;abord sur des mesures non-pharmacologiques (r&eacute;&eacute;ducation fonctionnelle&#x002C; exercices physiques et perte de poids en cas de surcharge pond&eacute;rale) &agrave; appliquer sur le long terme<span class='folia-referentie-nummer'><sup>3&#x002C;7&#x002C;9<\/sup><\/span>.<br \/> A court terme&#x002C; un traitement pharmacologique est possible&nbsp;comme par exemple un AINS &agrave; usage local (cf. <a href='https:\/\/www.cbip.be\/fr\/chapters\/10?frag=7211'>R&eacute;pertoire 9.4 Arthrose<\/a>).<\/p>\n<\/li>\n<\/ul>\n<p> &nbsp; <\/p>\n<h2>Sources<\/h2>\n<p><span class='folia-referentie-tekst'><\/span><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1<\/span>Pereira TV and al&#x002C; Viscosupplementation for knee osteoarthritis: systematic review and meta-analysis&#x002C; BMJ 2022;378:e069722. doi: 10.1136\/bmj-2022-069722. Voir aussi la discussion dans <a href='https:\/\/www.minerva-ebp.be\/FR\/Analysis\/826'>Minerva<\/a>.<\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>2&nbsp;<\/span>Peyron JG and al. Preliminary clinical assessment of Na-hyaluronate injection into human arthritic joints&#x002C; Pathol Biol 1974; 22(8): 31-6<br \/> <span class='folia-referentie-nummer'>3<\/span>&nbsp;<a href='https:\/\/www.dynamed.com\/management\/injection-therapy-for-osteoarthritis-oa-of-the-knee#GUID-2B8607EB-8C9B-4BD5-BD79-E47F3672C05D'>https:\/\/www.dynamed.com\/management\/injection-therapy-for-osteoarthritis-oa-of-the-knee#GUID-2B8607EB-8C9B-4BD5-BD79-E47F3672C05D<\/a><br \/> <span class='folia-referentie-nummer'>4<\/span>&nbsp;Sharma L. Osteoarthritis of the knee. N Engl J Med 2021;384:51-9. doi:10.1056\/NEJMcp1903768<br \/> <span class='folia-referentie-nummer'>5<\/span>&nbsp;Balazs EA. Viscosupplementation for treatment of osteoarthritis: from initial discovery to current status and results. Surg Technol Int 2004;12:278-89.<\/span><br \/> <span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>6<\/span>&nbsp;Rutjes AW and al. Viscosupplementation for osteoarthritis of the knee: a systematic review and meta-analysis. Ann Intern Med 2012;157:180-91. doi:10.7326\/0003-4819-157-3-201208070-00473<br \/> <span class='folia-referentie-nummer'>7&nbsp;<\/span>Katz JN&#x002C; Arant KR&#x002C; Loeser RF. Diagnosis and treatment of hip and knee osteoarthritis: a review. JAMA 2021;325:568-78. doi:10.1001\/jama.2020.22171<br \/> <span class='folia-referentie-nummer'>8<\/span>&nbsp;Wood G and all. Osteoarthritis in people over 16: diagnosis and management&mdash;updated summary of NICE guidance. BMJ 2023;380:p24 | doi: 10.1136\/bmj.p24<br \/> <span class='folia-referentie-nummer'>9<\/span>&nbsp;R&eacute;sum&eacute; des caract&eacute;ristiques du produits&#x002C; <a href='https:\/\/www.cbip.be\/fr\/chapters\/10?frag=25700&amp;trade_family=12476'>https:\/\/www.cbip.be\/fr\/chapters\/10?frag=25700&amp;trade_family=12476<\/a><br \/> <span class='folia-referentie-nummer'>10<\/span>&nbsp;Bellamy N and al. Viscosupplementation for the treatment of osteoarthritis of the knee. Cochrane Database of Systematic Reviews 2006&#x002C; Issue 2. Art. No.: CD005321.<br \/> DOI: 10.1002\/14651858.CD005321.pub2.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Message cl&eacute; Chez les patients souffrant d&#39;arthrose du genou&#x002C; une  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-186520","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186520"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186520\/revisions"}],"predecessor-version":[{"id":189077,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186520\/revisions\/189077"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}