{"id":186510,"date":"2023-11-23T00:00:00","date_gmt":"2023-11-22T23:00:00","guid":{"rendered":"https:\/\/www.bcfi.be\/vasoconstricteurs-oraux-deconseilles-dans-la-rhinite-selon-lansm\/"},"modified":"2026-07-09T15:11:55","modified_gmt":"2026-07-09T13:11:55","slug":"vasoconstricteurs-oraux-deconseilles-dans-la-rhinite-selon-lansm","status":"publish","type":"post","link":"https:\/\/h.cbip.be\/fr\/vasoconstricteurs-oraux-deconseilles-dans-la-rhinite-selon-lansm\/","title":{"rendered":"Vasoconstricteurs oraux d\u00e9conseill\u00e9s dans la rhinite selon l\u2019ANSM"},"content":{"rendered":"<p><b>L&rsquo;ANSM&#x002C; l&#39;agence fran&ccedil;aise du m&eacute;dicament&#x002C; d&eacute;conseille formellement<\/b> <b>le recours aux vasoconstricteurs oraux en cas de rhume&nbsp;<\/b>: voir <a href='https:\/\/ansm.sante.fr\/actualites\/en-cas-de-rhume-evitez-les-medicaments-vasoconstricteurs-par-voie-orale'>communiqu&eacute; du 22 octobre 2023<\/a>. En France&#x002C; ceci concerne la <b>pseudo&eacute;ph&eacute;drine<\/b>&#x002C; et en <b>Belgique<\/b>&#x002C; la <b>pseudo&eacute;ph&eacute;drine<\/b> (en monopr&eacute;paration et en pr&eacute;parations combin&eacute;es) et la <b>ph&eacute;nyl&eacute;phrine<\/b> (en pr&eacute;parations combin&eacute;es uniquement) (voir la liste des sp&eacute;cialit&eacute;s concern&eacute;es en fin d&rsquo;article).<\/p>\n<p>L&#39;ANSM&#x002C; qui met en garde depuis des ann&eacute;es contre le recours aux vasoconstricteurs oraux&#x002C; va aujourd&#39;hui plus loin en les d&eacute;conseillant formellement. En effet&#x002C; des cas (tr&egrave;s rares) d&#39;infarctus du myocarde et d&#39;accidents vasculaires c&eacute;r&eacute;braux continuent d&#39;&ecirc;tre rapport&eacute;s&#x002C; quelle que soit la dose ou la dur&eacute;e du traitement. Pour les pr&eacute;parations contenant de la pseudo&eacute;ph&eacute;drine&#x002C; il existe aussi un signal concernant la possibilit&eacute; de syndrome d&#39;enc&eacute;phalopathie r&eacute;versible post&eacute;rieure (PRES) et de syndrome de vasoconstriction c&eacute;r&eacute;brale r&eacute;versible (RCVS).&nbsp;<br \/> Nos coll&egrave;gues fran&ccedil;ais de la <b>Revue Prescrire<\/b> consid&egrave;rent que la d&eacute;cision de l&#39;ANSM de d&eacute;conseiller formellement les vasoconstricteurs oraux est un pas dans la bonne direction&#x002C; mais pr&eacute;f&eacute;reraient voir ces m&eacute;dicaments dispara&icirc;tre du march&eacute;.<sup><span class='folia-referentie-nummer'><sup>1<\/sup><\/span><\/sup><\/p>\n<p>Le<b> CBIP <\/b>soutient depuis des ann&eacute;es que le rapport b&eacute;n&eacute;fice\/risque des <b>vasoconstricteurs oraux <\/b>est d&eacute;favorable : il n&#39;y a pas de consensus sur leur efficacit&eacute; et leurs effets ind&eacute;sirables sont potentiellement tr&egrave;s graves. Outre les rares probl&egrave;mes cardiovasculaires mentionn&eacute;s ci-dessus&#x002C; il existe &eacute;galement des effets ind&eacute;sirables neuropsychiatriques et ophtalmologiques (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/18?frag=15743'>R&eacute;pertoire 17.3.1.<\/a>). De ce fait&#x002C; la place de ces m&eacute;dicaments n&#39;est pas indispensable dans les rhinosinusites qui gu&eacute;rissent spontan&eacute;ment en quelques semaines.<\/p>\n<p>&Agrave; la demande de l&#39;ANSM&#x002C; une <b>r&eacute;&eacute;valuation au niveau europ&eacute;en des risques et b&eacute;n&eacute;fices de la pseudo&eacute;ph&eacute;drine <\/b>est actuellement en cours (<a href='https:\/\/www.ema.europa.eu\/en\/medicines\/human\/referrals\/pseudoephedrine-containing-medicinal-products'>voir le site de l&#39;EMA<\/a>). Lorsque la r&eacute;&eacute;valuation sera finalis&eacute;e&#x002C; nous reviendrons sur ce sujet.<\/p>\n<h2> <b>Sources<\/b><\/h2>\n<p><span class='folia-referentie-tekst'><span class='folia-referentie-nummer'>1&nbsp;<\/span>La Revue Prescrire. Dans l&rsquo;actualit&eacute; &nbsp;&#8211; 24 octobre 2023&nbsp;: L&rsquo;ANSM d&eacute;conseille l&rsquo;utilisation des m&eacute;dicaments vasoconstricteurs encore autoris&eacute;s par voie orale dans le rhume. Via Application Prescrire<\/span><\/p>\n<h2><b>Noms des sp&eacute;cialit&eacute;s concern&eacute;es<\/b><\/h2>\n<ul>\n<li>\n<p>Ph&eacute;nyl&eacute;phrine par voie orale&nbsp;: en association avec un antihistaminique&nbsp;: Rhinathiol Antirhinitis&reg; (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/18?frag=20966'>R&eacute;pertoire<\/a>).<\/p>\n<\/li>\n<li>\n<p>Pseudo&eacute;ph&eacute;drine par voie orale&nbsp;: Vasocedine Pseudoephedrine&reg; (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/18?frag=20917'>R&eacute;pertoire<\/a>)&nbsp;; en association avec un antihistaminique&nbsp;: Aerinase&reg;&#x002C; Cirrus&reg;&#x002C; Clarinase&reg;&#x002C; Rhinosinutab&reg; (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/18?frag=20966'>R&eacute;pertoire<\/a>)&nbsp;; en association avec le parac&eacute;tamol&nbsp;: Parasineg&reg;&#x002C; Sinutab&reg;&#x002C; Therafixx-CapitaNasal&reg; (voir <a href='https:\/\/www.cbip.be\/fr\/chapters\/18?frag=20974'>R&eacute;pertoire<\/a>).<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ANSM&#x002C; l&#39;agence fran&ccedil;aise du m&eacute;dicament&#x002C; d&eacute;conseille formellement le recours aux  [&#8230;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,14914],"tags":[20213,20224],"class_list":["post-186510","post","type-post","status-publish","format-standard","hentry","category-actualites","category-2023-fr","tag-import_tags","tag-import_tags-nl"],"_links":{"self":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/comments?post=186510"}],"version-history":[{"count":1,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186510\/revisions"}],"predecessor-version":[{"id":189067,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/posts\/186510\/revisions\/189067"}],"wp:attachment":[{"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/media?parent=186510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/categories?post=186510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/h.cbip.be\/fr\/wp-json\/wp\/v2\/tags?post=186510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}